{"id":754,"date":"2025-07-11T02:55:11","date_gmt":"2025-07-11T07:55:11","guid":{"rendered":"https:\/\/dariojuris.com\/2025\/?page_id=754"},"modified":"2026-04-10T09:34:57","modified_gmt":"2026-04-10T14:34:57","slug":"medicina-estetica","status":"publish","type":"page","link":"https:\/\/dariojuris.com\/en\/medicina-estetica\/","title":{"rendered":"Aesthetic medicine"},"content":{"rendered":"<style>.kb-row-layout-id754_70ff1d-4f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id754_70ff1d-4f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id754_70ff1d-4f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-bottom:24px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id754_70ff1d-4f{background-image:url('https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/06\/Fondo-servicios.webp');background-size:cover;background-position:0% 50%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id754_70ff1d-4f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id754_70ff1d-4f > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id754_70ff1d-4f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id754_70ff1d-4f alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column754_971ca9-c9 > .kt-inside-inner-col{display:flex;}.kadence-column754_971ca9-c9 > .kt-inside-inner-col{padding-bottom:20px;}.kadence-column754_971ca9-c9 > .kt-inside-inner-col,.kadence-column754_971ca9-c9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column754_971ca9-c9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column754_971ca9-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column754_971ca9-c9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column754_971ca9-c9{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_971ca9-c9{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_971ca9-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column754_971ca9-c9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column754_971ca9-c9{position:relative;}.kadence-column754_971ca9-c9, .kt-inside-inner-col > .kadence-column754_971ca9-c9:not(.specificity){margin-top:80px;margin-left:20px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column754_971ca9-c9{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_971ca9-c9{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_971ca9-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column754_971ca9-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column754_971ca9-c9{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_971ca9-c9{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_971ca9-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column754_971ca9-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column754_971ca9-c9, .kt-inside-inner-col > .kadence-column754_971ca9-c9:not(.specificity){margin-top:50px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column754_971ca9-c9\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading754_ee0057-8d, .wp-block-kadence-advancedheading.kt-adv-heading754_ee0057-8d[data-kb-block=\"kb-adv-heading754_ee0057-8d\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading754_ee0057-8d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading754_ee0057-8d[data-kb-block=\"kb-adv-heading754_ee0057-8d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading754_ee0057-8d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading754_ee0057-8d[data-kb-block=\"kb-adv-heading754_ee0057-8d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading754_ee0057-8d, .wp-block-kadence-advancedheading.kt-adv-heading754_ee0057-8d[data-kb-block=\"kb-adv-heading754_ee0057-8d\"]{text-align:center!important;}}<\/style>\n<h6 class=\"kt-adv-heading754_ee0057-8d wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading754_ee0057-8d\">Servicios<\/h6>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading754_a1df33-7b, .wp-block-kadence-advancedheading.kt-adv-heading754_a1df33-7b[data-kb-block=\"kb-adv-heading754_a1df33-7b\"]{margin-top:-10px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading754_a1df33-7b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading754_a1df33-7b[data-kb-block=\"kb-adv-heading754_a1df33-7b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading754_a1df33-7b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading754_a1df33-7b[data-kb-block=\"kb-adv-heading754_a1df33-7b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading754_a1df33-7b, .wp-block-kadence-advancedheading.kt-adv-heading754_a1df33-7b[data-kb-block=\"kb-adv-heading754_a1df33-7b\"]{text-align:center!important;}}<\/style>\n<h2 class=\"kt-adv-heading754_a1df33-7b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading754_a1df33-7b\">Medicina est\u00e9tica<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column754_98ab85-ad > .kt-inside-inner-col{display:flex;}.kadence-column754_98ab85-ad > .kt-inside-inner-col,.kadence-column754_98ab85-ad > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column754_98ab85-ad > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column754_98ab85-ad > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-end;}.kadence-column754_98ab85-ad > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column754_98ab85-ad > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column754_98ab85-ad > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column754_98ab85-ad{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_98ab85-ad{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_98ab85-ad > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_98ab85-ad > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column754_98ab85-ad{position:relative;}.kadence-column754_98ab85-ad, .kt-inside-inner-col > .kadence-column754_98ab85-ad:not(.specificity){margin-top:-2px;margin-right:-70px;margin-bottom:-25px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column754_98ab85-ad{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_98ab85-ad{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_98ab85-ad > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column754_98ab85-ad > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-end;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column754_98ab85-ad{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_98ab85-ad{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_98ab85-ad > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_98ab85-ad > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column754_98ab85-ad kvs-sm-false\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image754_483c98-2a:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image754_483c98-2a .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image754_483c98-2a size-vp_md\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/hermosa-joven-tocando-su-rostro-concepto-de-juventud-y-cuidado-de-la-piel-Photoroom-800x533.png\" class=\"kb-img wp-image-841\"\/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id754_52aaab-56 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id754_52aaab-56 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id754_52aaab-56 > .kt-row-column-wrap{row-gap:var(--global-kb-gap-lg, 4rem);max-width:1390px;margin-left:auto;margin-right:auto;padding-top:80px;padding-bottom:80px;grid-template-columns:minmax(0, calc(50% - ((var(--kb-default-row-gutter, var(--global-row-gutter-md, 2rem)) * 1 )\/2)))minmax(0, calc(50% - ((var(--kb-default-row-gutter, var(--global-row-gutter-md, 2rem)) * 1 )\/2)));}.kb-row-layout-id754_52aaab-56 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id754_52aaab-56 > .kt-row-column-wrap{padding-top:60px;padding-right:50px;padding-bottom:60px;padding-left:50px;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id754_52aaab-56 > .kt-row-column-wrap{padding-top:80px;padding-right:30px;padding-bottom:50px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id754_52aaab-56 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column754_e90ec2-4a > .kt-inside-inner-col,.kadence-column754_e90ec2-4a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column754_e90ec2-4a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column754_e90ec2-4a > .kt-inside-inner-col{flex-direction:column;}.kadence-column754_e90ec2-4a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column754_e90ec2-4a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column754_e90ec2-4a{position:relative;}@media all and (max-width: 1024px){.kadence-column754_e90ec2-4a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column754_e90ec2-4a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column754_e90ec2-4a\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id754_41f8b6-24 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id754_41f8b6-24 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id754_41f8b6-24 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id754_41f8b6-24 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id754_41f8b6-24 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id754_41f8b6-24 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id754_41f8b6-24 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column754_8b5608-4a > .kt-inside-inner-col,.kadence-column754_8b5608-4a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column754_8b5608-4a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column754_8b5608-4a > .kt-inside-inner-col{flex-direction:column;}.kadence-column754_8b5608-4a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column754_8b5608-4a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column754_8b5608-4a{position:relative;}@media all and (max-width: 1024px){.kadence-column754_8b5608-4a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column754_8b5608-4a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column754_8b5608-4a\"><div class=\"kt-inside-inner-col\"><style>.kb-image754_1e8bc0-06 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-image754_1e8bc0-06 img.kb-img, .kb-image754_1e8bc0-06 .kb-img img{border-top:0px solid var(--global-palette2, #2B6CB0);border-right:0px solid var(--global-palette2, #2B6CB0);border-bottom:0px solid var(--global-palette2, #2B6CB0);border-left:0px solid var(--global-palette2, #2B6CB0);border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}@media all and (max-width: 1024px){.kb-image754_1e8bc0-06.kb-image-is-ratio-size, .kb-image754_1e8bc0-06 .kb-image-is-ratio-size{max-width:280px;width:100%;}}@media all and (max-width: 1024px){.kb-image754_1e8bc0-06 figure{max-width:280px;}}@media all and (max-width: 1024px){.kb-image754_1e8bc0-06 img.kb-img, .kb-image754_1e8bc0-06 .kb-img img{border-top:0px solid var(--global-palette2, #2B6CB0);border-right:0px solid var(--global-palette2, #2B6CB0);border-bottom:0px solid var(--global-palette2, #2B6CB0);border-left:0px solid var(--global-palette2, #2B6CB0);}}@media all and (max-width: 767px){.kb-image754_1e8bc0-06.kb-image-is-ratio-size, .kb-image754_1e8bc0-06 .kb-image-is-ratio-size{max-width:711px;width:100%;}.kb-image754_1e8bc0-06 figure{max-width:711px;}.kb-image754_1e8bc0-06 img.kb-img, .kb-image754_1e8bc0-06 .kb-img img{border-top:0px solid var(--global-palette2, #2B6CB0);border-right:0px solid var(--global-palette2, #2B6CB0);border-bottom:0px solid var(--global-palette2, #2B6CB0);border-left:0px solid var(--global-palette2, #2B6CB0);}}<\/style>\n<div class=\"wp-block-kadence-image kb-image754_1e8bc0-06\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"287\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/06\/Bichectomia.webp\" alt=\"\" class=\"kb-img wp-image-367\"\/><\/figure><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column754_854235-40 > .kt-inside-inner-col{display:flex;}.kadence-column754_854235-40 > .kt-inside-inner-col,.kadence-column754_854235-40 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column754_854235-40 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column754_854235-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_854235-40 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column754_854235-40{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_854235-40{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_854235-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_854235-40 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column754_854235-40{position:relative;}.kadence-column754_854235-40, .kt-inside-inner-col > .kadence-column754_854235-40:not(.specificity){margin-left:-30px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column754_854235-40{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_854235-40{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_854235-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column754_854235-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column754_854235-40{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_854235-40{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_854235-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_854235-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_854235-40, .kt-inside-inner-col > .kadence-column754_854235-40:not(.specificity){margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column754_854235-40\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading754_1c2a79-31, .wp-block-kadence-advancedheading.kt-adv-heading754_1c2a79-31[data-kb-block=\"kb-adv-heading754_1c2a79-31\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading754_1c2a79-31 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading754_1c2a79-31[data-kb-block=\"kb-adv-heading754_1c2a79-31\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading754_1c2a79-31 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading754_1c2a79-31[data-kb-block=\"kb-adv-heading754_1c2a79-31\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading754_1c2a79-31, .wp-block-kadence-advancedheading.kt-adv-heading754_1c2a79-31[data-kb-block=\"kb-adv-heading754_1c2a79-31\"]{text-align:center!important;}}<\/style>\n<h3 class=\"kt-adv-heading754_1c2a79-31 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading754_1c2a79-31\"><strong>\u00c1cido Hialur\u00f3nico<\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading754_15e583-52, .wp-block-kadence-advancedheading.kt-adv-heading754_15e583-52[data-kb-block=\"kb-adv-heading754_15e583-52\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading754_15e583-52 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading754_15e583-52[data-kb-block=\"kb-adv-heading754_15e583-52\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading754_15e583-52 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading754_15e583-52[data-kb-block=\"kb-adv-heading754_15e583-52\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading754_15e583-52, .wp-block-kadence-advancedheading.kt-adv-heading754_15e583-52[data-kb-block=\"kb-adv-heading754_15e583-52\"]{text-align:center!important;}}<\/style>\n<p class=\"kt-adv-heading754_15e583-52 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading754_15e583-52\">Cumple una funci\u00f3n hidratante, estimula la circulaci\u00f3n perif\u00e9rica, revitaliza el ciclo celular y restituye al rostro luz y suavidad.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns754_2bfdec-cd, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns754_2bfdec-cd, .wp-block-kadence-advancedbtn.kb-btns754_2bfdec-cd, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns754_2bfdec-cd{margin-top:-20px;margin-right:-50px;}.wp-block-kadence-advancedbtn.kb-btns754_2bfdec-cd{gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:row;justify-content:flex-start;align-items:center;}.kt-btns754_2bfdec-cd .kt-button{font-weight:normal;font-style:normal;}.kt-btns754_2bfdec-cd .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns754_2bfdec-cd .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns754_2bfdec-cd .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns754_2bfdec-cd .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns754_2bfdec-cd .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns754_2bfdec-cd .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns754_2bfdec-cd .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kt-btns754_2bfdec-cd, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns754_2bfdec-cd, .wp-block-kadence-advancedbtn.kb-btns754_2bfdec-cd, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns754_2bfdec-cd{margin-right:0px;}.wp-block-kadence-advancedbtn.kb-btns754_2bfdec-cd{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns754_2bfdec-cd\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn754_9e5824-56.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn754_9e5824-56.kb-button{border-top-left-radius:100px;border-top-right-radius:100px;border-bottom-right-radius:100px;border-bottom-left-radius:100px;}<\/style><a class=\"kb-button kt-button button kb-btn754_9e5824-56 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/wa.me\/573187777129\"><span class=\"kt-btn-inner-text\">Agenda tu cita<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn754_9f13bb-1d.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn754_9f13bb-1d.kb-button{background:var(--global-palette8, #F7FAFC);border-top-left-radius:100px;border-top-right-radius:100px;border-bottom-right-radius:100px;border-bottom-left-radius:100px;}.wp-block-kadence-advancedbtn .kb-btn754_9f13bb-1d.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn754_9f13bb-1d.kb-button:focus{background:var(--global-palette7, #EDF2F7);}<\/style><a class=\"kb-button kt-button button kb-btn754_9f13bb-1d kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/dariojuris.com\/portfolio\/acido-hialuronico\/\"><span class=\"kt-btn-inner-text\">M\u00e1s informaci\u00f3n<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column754_a6cb23-f5 > .kt-inside-inner-col,.kadence-column754_a6cb23-f5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column754_a6cb23-f5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column754_a6cb23-f5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column754_a6cb23-f5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column754_a6cb23-f5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column754_a6cb23-f5{position:relative;}@media all and (max-width: 1024px){.kadence-column754_a6cb23-f5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column754_a6cb23-f5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column754_a6cb23-f5\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id754_a77be9-e5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id754_a77be9-e5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id754_a77be9-e5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id754_a77be9-e5 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id754_a77be9-e5 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id754_a77be9-e5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id754_a77be9-e5 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column754_054256-7a > .kt-inside-inner-col,.kadence-column754_054256-7a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column754_054256-7a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column754_054256-7a > .kt-inside-inner-col{flex-direction:column;}.kadence-column754_054256-7a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column754_054256-7a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column754_054256-7a{position:relative;}@media all and (max-width: 1024px){.kadence-column754_054256-7a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column754_054256-7a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column754_054256-7a\"><div class=\"kt-inside-inner-col\"><style>.kb-image754_6d82c4-79 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-image754_6d82c4-79 img.kb-img, .kb-image754_6d82c4-79 .kb-img img{border-top:0px solid var(--global-palette2, #2B6CB0);border-right:0px solid var(--global-palette2, #2B6CB0);border-bottom:0px solid var(--global-palette2, #2B6CB0);border-left:0px solid var(--global-palette2, #2B6CB0);border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}@media all and (max-width: 1024px){.kb-image754_6d82c4-79 img.kb-img, .kb-image754_6d82c4-79 .kb-img img{border-top:0px solid var(--global-palette2, #2B6CB0);border-right:0px solid var(--global-palette2, #2B6CB0);border-bottom:0px solid var(--global-palette2, #2B6CB0);border-left:0px solid var(--global-palette2, #2B6CB0);}}@media all and (max-width: 767px){.kb-image754_6d82c4-79 img.kb-img, .kb-image754_6d82c4-79 .kb-img img{border-top:0px solid var(--global-palette2, #2B6CB0);border-right:0px solid var(--global-palette2, #2B6CB0);border-bottom:0px solid var(--global-palette2, #2B6CB0);border-left:0px solid var(--global-palette2, #2B6CB0);}}<\/style>\n<div class=\"wp-block-kadence-image kb-image754_6d82c4-79\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/2149152755-686dff2e6b6a6-200x300.webp\" class=\"kb-img wp-image-623\" srcset=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/2149152755-686dff2e6b6a6-200x300.webp 200w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/2149152755-686dff2e6b6a6-682x1024.webp 682w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/2149152755-686dff2e6b6a6-768x1152.webp 768w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/2149152755-686dff2e6b6a6-1024x1536.webp 1024w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/2149152755-686dff2e6b6a6-500x750.webp 500w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/2149152755-686dff2e6b6a6-800x1200.webp 800w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/2149152755-686dff2e6b6a6-1280x1920.webp 1280w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/2149152755-686dff2e6b6a6.webp 1333w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column754_fa90bb-ee > .kt-inside-inner-col{display:flex;}.kadence-column754_fa90bb-ee > .kt-inside-inner-col,.kadence-column754_fa90bb-ee > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column754_fa90bb-ee > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column754_fa90bb-ee > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_fa90bb-ee > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column754_fa90bb-ee{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_fa90bb-ee{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_fa90bb-ee > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_fa90bb-ee > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column754_fa90bb-ee{position:relative;}.kadence-column754_fa90bb-ee, .kt-inside-inner-col > .kadence-column754_fa90bb-ee:not(.specificity){margin-left:-30px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column754_fa90bb-ee{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_fa90bb-ee{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_fa90bb-ee > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column754_fa90bb-ee > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column754_fa90bb-ee{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_fa90bb-ee{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_fa90bb-ee > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_fa90bb-ee > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_fa90bb-ee, .kt-inside-inner-col > .kadence-column754_fa90bb-ee:not(.specificity){margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column754_fa90bb-ee\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading754_df000f-4f, .wp-block-kadence-advancedheading.kt-adv-heading754_df000f-4f[data-kb-block=\"kb-adv-heading754_df000f-4f\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading754_df000f-4f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading754_df000f-4f[data-kb-block=\"kb-adv-heading754_df000f-4f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading754_df000f-4f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading754_df000f-4f[data-kb-block=\"kb-adv-heading754_df000f-4f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading754_df000f-4f, .wp-block-kadence-advancedheading.kt-adv-heading754_df000f-4f[data-kb-block=\"kb-adv-heading754_df000f-4f\"]{text-align:center!important;}}<\/style>\n<h3 class=\"kt-adv-heading754_df000f-4f wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading754_df000f-4f\"><strong>Implante Capilar<\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading754_a3a207-75, .wp-block-kadence-advancedheading.kt-adv-heading754_a3a207-75[data-kb-block=\"kb-adv-heading754_a3a207-75\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading754_a3a207-75 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading754_a3a207-75[data-kb-block=\"kb-adv-heading754_a3a207-75\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading754_a3a207-75 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading754_a3a207-75[data-kb-block=\"kb-adv-heading754_a3a207-75\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading754_a3a207-75, .wp-block-kadence-advancedheading.kt-adv-heading754_a3a207-75[data-kb-block=\"kb-adv-heading754_a3a207-75\"]{text-align:center!important;}}<\/style>\n<p class=\"kt-adv-heading754_a3a207-75 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading754_a3a207-75\">Historicamente, el cabello ha sido una fuente de orgullo para los hombres y es una carcteristica distintiva que adorna y protege.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns754_8aabba-37, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns754_8aabba-37, .wp-block-kadence-advancedbtn.kb-btns754_8aabba-37, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns754_8aabba-37{margin-top:-20px;margin-right:-50px;}.wp-block-kadence-advancedbtn.kb-btns754_8aabba-37{gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:row;justify-content:flex-start;align-items:center;}.kt-btns754_8aabba-37 .kt-button{font-weight:normal;font-style:normal;}.kt-btns754_8aabba-37 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns754_8aabba-37 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns754_8aabba-37 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns754_8aabba-37 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns754_8aabba-37 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns754_8aabba-37 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns754_8aabba-37 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kt-btns754_8aabba-37, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns754_8aabba-37, .wp-block-kadence-advancedbtn.kb-btns754_8aabba-37, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns754_8aabba-37{margin-right:0px;}.wp-block-kadence-advancedbtn.kb-btns754_8aabba-37{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns754_8aabba-37\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn754_88be7d-72.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn754_88be7d-72.kb-button{border-top-left-radius:100px;border-top-right-radius:100px;border-bottom-right-radius:100px;border-bottom-left-radius:100px;}<\/style><a class=\"kb-button kt-button button kb-btn754_88be7d-72 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/wa.me\/573187777129\"><span class=\"kt-btn-inner-text\">Agenda tu cita<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn754_597661-20.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn754_597661-20.kb-button{background:var(--global-palette8, #F7FAFC);border-top-left-radius:100px;border-top-right-radius:100px;border-bottom-right-radius:100px;border-bottom-left-radius:100px;}.wp-block-kadence-advancedbtn .kb-btn754_597661-20.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn754_597661-20.kb-button:focus{background:var(--global-palette7, #EDF2F7);}<\/style><a class=\"kb-button kt-button button kb-btn754_597661-20 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/dariojuris.com\/portfolio\/implante-capilar\/\"><span class=\"kt-btn-inner-text\">M\u00e1s informaci\u00f3n<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column754_08a614-81 > .kt-inside-inner-col,.kadence-column754_08a614-81 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column754_08a614-81 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column754_08a614-81 > .kt-inside-inner-col{flex-direction:column;}.kadence-column754_08a614-81 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column754_08a614-81 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column754_08a614-81{position:relative;}@media all and (max-width: 1024px){.kadence-column754_08a614-81 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column754_08a614-81 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column754_08a614-81\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id754_4e27a8-42 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id754_4e27a8-42 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id754_4e27a8-42 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id754_4e27a8-42 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id754_4e27a8-42 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id754_4e27a8-42 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id754_4e27a8-42 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column754_0ecca7-05 > .kt-inside-inner-col,.kadence-column754_0ecca7-05 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column754_0ecca7-05 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column754_0ecca7-05 > .kt-inside-inner-col{flex-direction:column;}.kadence-column754_0ecca7-05 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column754_0ecca7-05 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column754_0ecca7-05{position:relative;}@media all and (max-width: 1024px){.kadence-column754_0ecca7-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column754_0ecca7-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column754_0ecca7-05\"><div class=\"kt-inside-inner-col\"><style>.kb-image754_844cb3-a2 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-image754_844cb3-a2 img.kb-img, .kb-image754_844cb3-a2 .kb-img img{border-top:0px solid var(--global-palette2, #2B6CB0);border-right:0px solid var(--global-palette2, #2B6CB0);border-bottom:0px solid var(--global-palette2, #2B6CB0);border-left:0px solid var(--global-palette2, #2B6CB0);border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}@media all and (max-width: 1024px){.kb-image754_844cb3-a2 img.kb-img, .kb-image754_844cb3-a2 .kb-img img{border-top:0px solid var(--global-palette2, #2B6CB0);border-right:0px solid var(--global-palette2, #2B6CB0);border-bottom:0px solid var(--global-palette2, #2B6CB0);border-left:0px solid var(--global-palette2, #2B6CB0);}}@media all and (max-width: 767px){.kb-image754_844cb3-a2 img.kb-img, .kb-image754_844cb3-a2 .kb-img img{border-top:0px solid var(--global-palette2, #2B6CB0);border-right:0px solid var(--global-palette2, #2B6CB0);border-bottom:0px solid var(--global-palette2, #2B6CB0);border-left:0px solid var(--global-palette2, #2B6CB0);}}<\/style>\n<div class=\"wp-block-kadence-image kb-image754_844cb3-a2\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"223\" height=\"300\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/recurso-22-6870b1107f2f2-223x300.webp\" class=\"kb-img wp-image-698\" srcset=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/recurso-22-6870b1107f2f2-223x300.webp 223w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/recurso-22-6870b1107f2f2.webp 282w\" sizes=\"auto, (max-width: 223px) 100vw, 223px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column754_69b8c2-cc > .kt-inside-inner-col{display:flex;}.kadence-column754_69b8c2-cc > .kt-inside-inner-col,.kadence-column754_69b8c2-cc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column754_69b8c2-cc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column754_69b8c2-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_69b8c2-cc > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column754_69b8c2-cc{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_69b8c2-cc{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_69b8c2-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_69b8c2-cc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column754_69b8c2-cc{position:relative;}.kadence-column754_69b8c2-cc, .kt-inside-inner-col > .kadence-column754_69b8c2-cc:not(.specificity){margin-left:-30px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column754_69b8c2-cc{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_69b8c2-cc{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_69b8c2-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column754_69b8c2-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column754_69b8c2-cc{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_69b8c2-cc{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_69b8c2-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_69b8c2-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_69b8c2-cc, .kt-inside-inner-col > .kadence-column754_69b8c2-cc:not(.specificity){margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column754_69b8c2-cc\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading754_037dc1-a9, .wp-block-kadence-advancedheading.kt-adv-heading754_037dc1-a9[data-kb-block=\"kb-adv-heading754_037dc1-a9\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading754_037dc1-a9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading754_037dc1-a9[data-kb-block=\"kb-adv-heading754_037dc1-a9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading754_037dc1-a9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading754_037dc1-a9[data-kb-block=\"kb-adv-heading754_037dc1-a9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading754_037dc1-a9, .wp-block-kadence-advancedheading.kt-adv-heading754_037dc1-a9[data-kb-block=\"kb-adv-heading754_037dc1-a9\"]{text-align:center!important;}}<\/style>\n<h3 class=\"kt-adv-heading754_037dc1-a9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading754_037dc1-a9\"><strong>Radiesse<\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading754_174939-6e, .wp-block-kadence-advancedheading.kt-adv-heading754_174939-6e[data-kb-block=\"kb-adv-heading754_174939-6e\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading754_174939-6e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading754_174939-6e[data-kb-block=\"kb-adv-heading754_174939-6e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading754_174939-6e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading754_174939-6e[data-kb-block=\"kb-adv-heading754_174939-6e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading754_174939-6e, .wp-block-kadence-advancedheading.kt-adv-heading754_174939-6e[data-kb-block=\"kb-adv-heading754_174939-6e\"]{text-align:center!important;}}<\/style>\n<p class=\"kt-adv-heading754_174939-6e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading754_174939-6e\">El col\u00e1geno es la principal prote\u00edna estructural de nuestra piel, responsable de mantenerla firme y radiante.\u00a0<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns754_a44765-d7, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns754_a44765-d7, .wp-block-kadence-advancedbtn.kb-btns754_a44765-d7, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns754_a44765-d7{margin-top:-20px;margin-right:-50px;}.wp-block-kadence-advancedbtn.kb-btns754_a44765-d7{gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:row;justify-content:flex-start;align-items:center;}.kt-btns754_a44765-d7 .kt-button{font-weight:normal;font-style:normal;}.kt-btns754_a44765-d7 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns754_a44765-d7 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns754_a44765-d7 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns754_a44765-d7 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns754_a44765-d7 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns754_a44765-d7 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns754_a44765-d7 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kt-btns754_a44765-d7, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns754_a44765-d7, .wp-block-kadence-advancedbtn.kb-btns754_a44765-d7, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns754_a44765-d7{margin-right:0px;}.wp-block-kadence-advancedbtn.kb-btns754_a44765-d7{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns754_a44765-d7\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn754_e38881-8f.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn754_e38881-8f.kb-button{border-top-left-radius:100px;border-top-right-radius:100px;border-bottom-right-radius:100px;border-bottom-left-radius:100px;}<\/style><a class=\"kb-button kt-button button kb-btn754_e38881-8f kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/wa.me\/573187777129\"><span class=\"kt-btn-inner-text\">Agenda tu cita<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn754_77971a-73.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn754_77971a-73.kb-button{background:var(--global-palette8, #F7FAFC);border-top-left-radius:100px;border-top-right-radius:100px;border-bottom-right-radius:100px;border-bottom-left-radius:100px;}.wp-block-kadence-advancedbtn .kb-btn754_77971a-73.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn754_77971a-73.kb-button:focus{background:var(--global-palette7, #EDF2F7);}<\/style><span class=\"kb-button kt-button button kb-btn754_77971a-73 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">M\u00e1s informaci\u00f3n<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column754_0d774d-f6 > .kt-inside-inner-col{display:flex;}.kadence-column754_0d774d-f6 > .kt-inside-inner-col,.kadence-column754_0d774d-f6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column754_0d774d-f6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column754_0d774d-f6 > .kt-inside-inner-col{flex-direction:column;align-items:flex-end;}.kadence-column754_0d774d-f6 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column754_0d774d-f6 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column754_0d774d-f6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column754_0d774d-f6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column754_0d774d-f6{position:relative;}@media all and (max-width: 1024px){.kadence-column754_0d774d-f6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-end;}}@media all and (max-width: 767px){.kadence-column754_0d774d-f6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column754_0d774d-f6\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id754_eef216-95 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id754_eef216-95 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id754_eef216-95 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id754_eef216-95 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id754_eef216-95 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id754_eef216-95 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id754_eef216-95 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column754_cf322a-37 > .kt-inside-inner-col,.kadence-column754_cf322a-37 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column754_cf322a-37 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column754_cf322a-37 > .kt-inside-inner-col{flex-direction:column;}.kadence-column754_cf322a-37 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column754_cf322a-37 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column754_cf322a-37{position:relative;}@media all and (max-width: 1024px){.kadence-column754_cf322a-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column754_cf322a-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column754_cf322a-37\"><div class=\"kt-inside-inner-col\"><style>.kb-image754_b9b66a-a0 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-image754_b9b66a-a0 img.kb-img, .kb-image754_b9b66a-a0 .kb-img img{border-top:0px solid var(--global-palette2, #2B6CB0);border-right:0px solid var(--global-palette2, #2B6CB0);border-bottom:0px solid var(--global-palette2, #2B6CB0);border-left:0px solid var(--global-palette2, #2B6CB0);border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}@media all and (max-width: 1024px){.kb-image754_b9b66a-a0.kb-image-is-ratio-size, .kb-image754_b9b66a-a0 .kb-image-is-ratio-size{max-width:280px;width:100%;}}@media all and (max-width: 1024px){.kb-image754_b9b66a-a0 figure{max-width:280px;}}@media all and (max-width: 1024px){.kb-image754_b9b66a-a0 img.kb-img, .kb-image754_b9b66a-a0 .kb-img img{border-top:0px solid var(--global-palette2, #2B6CB0);border-right:0px solid var(--global-palette2, #2B6CB0);border-bottom:0px solid var(--global-palette2, #2B6CB0);border-left:0px solid var(--global-palette2, #2B6CB0);}}@media all and (max-width: 767px){.kb-image754_b9b66a-a0.kb-image-is-ratio-size, .kb-image754_b9b66a-a0 .kb-image-is-ratio-size{max-width:711px;width:100%;}.kb-image754_b9b66a-a0 figure{max-width:711px;}.kb-image754_b9b66a-a0 img.kb-img, .kb-image754_b9b66a-a0 .kb-img img{border-top:0px solid var(--global-palette2, #2B6CB0);border-right:0px solid var(--global-palette2, #2B6CB0);border-bottom:0px solid var(--global-palette2, #2B6CB0);border-left:0px solid var(--global-palette2, #2B6CB0);}}<\/style>\n<div class=\"wp-block-kadence-image kb-image754_b9b66a-a0\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"287\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/Otoplastia.webp\" alt=\"\" class=\"kb-img wp-image-394\"\/><\/figure><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column754_11977d-d1 > .kt-inside-inner-col{display:flex;}.kadence-column754_11977d-d1 > .kt-inside-inner-col,.kadence-column754_11977d-d1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column754_11977d-d1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column754_11977d-d1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_11977d-d1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column754_11977d-d1{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_11977d-d1{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_11977d-d1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_11977d-d1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column754_11977d-d1{position:relative;}.kadence-column754_11977d-d1, .kt-inside-inner-col > .kadence-column754_11977d-d1:not(.specificity){margin-left:-30px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column754_11977d-d1{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_11977d-d1{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_11977d-d1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column754_11977d-d1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column754_11977d-d1{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_11977d-d1{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column754_11977d-d1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_11977d-d1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column754_11977d-d1, .kt-inside-inner-col > .kadence-column754_11977d-d1:not(.specificity){margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column754_11977d-d1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading754_238811-65, .wp-block-kadence-advancedheading.kt-adv-heading754_238811-65[data-kb-block=\"kb-adv-heading754_238811-65\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading754_238811-65 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading754_238811-65[data-kb-block=\"kb-adv-heading754_238811-65\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading754_238811-65 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading754_238811-65[data-kb-block=\"kb-adv-heading754_238811-65\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading754_238811-65, .wp-block-kadence-advancedheading.kt-adv-heading754_238811-65[data-kb-block=\"kb-adv-heading754_238811-65\"]{text-align:center!important;}}<\/style>\n<h3 class=\"kt-adv-heading754_238811-65 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading754_238811-65\"><strong>Toxina Botul\u00ednica<\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading754_7b106d-a6, .wp-block-kadence-advancedheading.kt-adv-heading754_7b106d-a6[data-kb-block=\"kb-adv-heading754_7b106d-a6\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading754_7b106d-a6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading754_7b106d-a6[data-kb-block=\"kb-adv-heading754_7b106d-a6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading754_7b106d-a6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading754_7b106d-a6[data-kb-block=\"kb-adv-heading754_7b106d-a6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading754_7b106d-a6, .wp-block-kadence-advancedheading.kt-adv-heading754_7b106d-a6[data-kb-block=\"kb-adv-heading754_7b106d-a6\"]{text-align:center!important;}}<\/style>\n<p class=\"kt-adv-heading754_7b106d-a6 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading754_7b106d-a6\">Las arrugas faciales son la expresi\u00f3n natural del proceso de envejecimiento de los tejidos, de la acci\u00f3n de los m\u00fasculos<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns754_bb61a2-f2, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns754_bb61a2-f2, .wp-block-kadence-advancedbtn.kb-btns754_bb61a2-f2, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns754_bb61a2-f2{margin-top:-20px;margin-right:-50px;}.wp-block-kadence-advancedbtn.kb-btns754_bb61a2-f2{gap:var(--global-kb-gap-xs, 0.5rem );flex-direction:row;justify-content:flex-start;align-items:center;}.kt-btns754_bb61a2-f2 .kt-button{font-weight:normal;font-style:normal;}.kt-btns754_bb61a2-f2 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns754_bb61a2-f2 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns754_bb61a2-f2 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns754_bb61a2-f2 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns754_bb61a2-f2 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns754_bb61a2-f2 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns754_bb61a2-f2 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kt-btns754_bb61a2-f2, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns754_bb61a2-f2, .wp-block-kadence-advancedbtn.kb-btns754_bb61a2-f2, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns754_bb61a2-f2{margin-right:0px;}.wp-block-kadence-advancedbtn.kb-btns754_bb61a2-f2{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns754_bb61a2-f2\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn754_574574-e1.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn754_574574-e1.kb-button{border-top-left-radius:100px;border-top-right-radius:100px;border-bottom-right-radius:100px;border-bottom-left-radius:100px;}<\/style><a class=\"kb-button kt-button button kb-btn754_574574-e1 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/wa.me\/573187777129\"><span class=\"kt-btn-inner-text\">Agenda tu cita<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn754_b095b8-33.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn754_b095b8-33.kb-button{background:var(--global-palette8, #F7FAFC);border-top-left-radius:100px;border-top-right-radius:100px;border-bottom-right-radius:100px;border-bottom-left-radius:100px;}.wp-block-kadence-advancedbtn .kb-btn754_b095b8-33.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn754_b095b8-33.kb-button:focus{background:var(--global-palette7, #EDF2F7);}<\/style><a class=\"kb-button kt-button button kb-btn754_b095b8-33 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/dariojuris.com\/portfolio\/toxina-botulinica\/\"><span class=\"kt-btn-inner-text\">M\u00e1s informaci\u00f3n<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Servicios Medicina est\u00e9tica \u00c1cido Hialur\u00f3nico Cumple una funci\u00f3n hidratante, estimula la circulaci\u00f3n perif\u00e9rica, revitaliza el ciclo celular y restituye al rostro luz y suavidad. Implante Capilar Historicamente, el cabello ha sido una fuente de orgullo para los hombres y es una carcteristica distintiva que adorna y protege. Radiesse El col\u00e1geno es la principal prote\u00edna estructural&#8230;<\/p>","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"disable","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_vp_format_video_url":"","_vp_image_focal_point":[],"_joinchat":[],"footnotes":""},"class_list":["post-754","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Medicina est\u00e9tica - DR. Dario Juris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dariojuris.com\/en\/medicina-estetica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medicina est\u00e9tica - DR. Dario Juris\" \/>\n<meta property=\"og:description\" content=\"Servicios Medicina est\u00e9tica \u00c1cido Hialur\u00f3nico Cumple una funci\u00f3n hidratante, estimula la circulaci\u00f3n perif\u00e9rica, revitaliza el ciclo celular y restituye al rostro luz y suavidad. Implante Capilar Historicamente, el cabello ha sido una fuente de orgullo para los hombres y es una carcteristica distintiva que adorna y protege. Radiesse El col\u00e1geno es la principal prote\u00edna estructural...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dariojuris.com\/en\/medicina-estetica\/\" \/>\n<meta property=\"og:site_name\" content=\"DR. Dario Juris\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T14:34:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/hermosa-joven-tocando-su-rostro-concepto-de-juventud-y-cuidado-de-la-piel-Photoroom-e1752235917876.png\" \/>\n\t<meta property=\"og:image:width\" content=\"535\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dariojuris.com\\\/medicina-estetica\\\/\",\"url\":\"https:\\\/\\\/dariojuris.com\\\/medicina-estetica\\\/\",\"name\":\"Medicina est\u00e9tica - DR. Dario Juris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dariojuris.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dariojuris.com\\\/medicina-estetica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dariojuris.com\\\/medicina-estetica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dariojuris.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/hermosa-joven-tocando-su-rostro-concepto-de-juventud-y-cuidado-de-la-piel-Photoroom-800x533.png\",\"datePublished\":\"2025-07-11T07:55:11+00:00\",\"dateModified\":\"2026-04-10T14:34:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dariojuris.com\\\/medicina-estetica\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dariojuris.com\\\/medicina-estetica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dariojuris.com\\\/medicina-estetica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dariojuris.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/hermosa-joven-tocando-su-rostro-concepto-de-juventud-y-cuidado-de-la-piel-Photoroom-800x533.png\",\"contentUrl\":\"https:\\\/\\\/dariojuris.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/hermosa-joven-tocando-su-rostro-concepto-de-juventud-y-cuidado-de-la-piel-Photoroom-800x533.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dariojuris.com\\\/medicina-estetica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dariojuris.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medicina est\u00e9tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dariojuris.com\\\/#website\",\"url\":\"https:\\\/\\\/dariojuris.com\\\/\",\"name\":\"DR. Dario Juris\",\"description\":\"Dr. Dar\u00edo Juris \u2013 Cirujano pl\u00e1stico en Bogot\u00e1 con m\u00e1s de 14 a\u00f1os de experiencia y m\u00e1s de 4.000 intervenciones, especializado en procedimientos faciales y corporales como rinoplastia, aumento de senos, liposucci\u00f3n y abdominoplastia. Miembro de la SCCP, ISAPS y FILAP, ofrece seguridad y excelencia quir\u00fargica en cl\u00ednicas reconocidas de Bogot\u00e1.\",\"publisher\":{\"@id\":\"https:\\\/\\\/dariojuris.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dariojuris.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dariojuris.com\\\/#organization\",\"name\":\"DR. Dario Juris\",\"url\":\"https:\\\/\\\/dariojuris.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dariojuris.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dariojuris.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/image-6852c92cc59ea.webp\",\"contentUrl\":\"https:\\\/\\\/dariojuris.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/image-6852c92cc59ea.webp\",\"width\":85,\"height\":88,\"caption\":\"DR. Dario Juris\"},\"image\":{\"@id\":\"https:\\\/\\\/dariojuris.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medicina est\u00e9tica - DR. Dario Juris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dariojuris.com\/en\/medicina-estetica\/","og_locale":"en_US","og_type":"article","og_title":"Medicina est\u00e9tica - DR. Dario Juris","og_description":"Servicios Medicina est\u00e9tica \u00c1cido Hialur\u00f3nico Cumple una funci\u00f3n hidratante, estimula la circulaci\u00f3n perif\u00e9rica, revitaliza el ciclo celular y restituye al rostro luz y suavidad. Implante Capilar Historicamente, el cabello ha sido una fuente de orgullo para los hombres y es una carcteristica distintiva que adorna y protege. Radiesse El col\u00e1geno es la principal prote\u00edna estructural...","og_url":"https:\/\/dariojuris.com\/en\/medicina-estetica\/","og_site_name":"DR. Dario Juris","article_modified_time":"2026-04-10T14:34:57+00:00","og_image":[{"width":535,"height":853,"url":"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/hermosa-joven-tocando-su-rostro-concepto-de-juventud-y-cuidado-de-la-piel-Photoroom-e1752235917876.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dariojuris.com\/medicina-estetica\/","url":"https:\/\/dariojuris.com\/medicina-estetica\/","name":"Medicina est\u00e9tica - DR. Dario Juris","isPartOf":{"@id":"https:\/\/dariojuris.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dariojuris.com\/medicina-estetica\/#primaryimage"},"image":{"@id":"https:\/\/dariojuris.com\/medicina-estetica\/#primaryimage"},"thumbnailUrl":"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/hermosa-joven-tocando-su-rostro-concepto-de-juventud-y-cuidado-de-la-piel-Photoroom-800x533.png","datePublished":"2025-07-11T07:55:11+00:00","dateModified":"2026-04-10T14:34:57+00:00","breadcrumb":{"@id":"https:\/\/dariojuris.com\/medicina-estetica\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dariojuris.com\/medicina-estetica\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dariojuris.com\/medicina-estetica\/#primaryimage","url":"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/hermosa-joven-tocando-su-rostro-concepto-de-juventud-y-cuidado-de-la-piel-Photoroom-800x533.png","contentUrl":"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/hermosa-joven-tocando-su-rostro-concepto-de-juventud-y-cuidado-de-la-piel-Photoroom-800x533.png"},{"@type":"BreadcrumbList","@id":"https:\/\/dariojuris.com\/medicina-estetica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dariojuris.com\/"},{"@type":"ListItem","position":2,"name":"Medicina est\u00e9tica"}]},{"@type":"WebSite","@id":"https:\/\/dariojuris.com\/#website","url":"https:\/\/dariojuris.com\/","name":"DR. Dario Juris","description":"Dr. Dar\u00edo Juris \u2013 Cirujano pl\u00e1stico en Bogot\u00e1 con m\u00e1s de 14 a\u00f1os de experiencia y m\u00e1s de 4.000 intervenciones, especializado en procedimientos faciales y corporales como rinoplastia, aumento de senos, liposucci\u00f3n y abdominoplastia. Miembro de la SCCP, ISAPS y FILAP, ofrece seguridad y excelencia quir\u00fargica en cl\u00ednicas reconocidas de Bogot\u00e1.","publisher":{"@id":"https:\/\/dariojuris.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dariojuris.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dariojuris.com\/#organization","name":"DR. Dario Juris","url":"https:\/\/dariojuris.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dariojuris.com\/#\/schema\/logo\/image\/","url":"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/06\/image-6852c92cc59ea.webp","contentUrl":"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/06\/image-6852c92cc59ea.webp","width":85,"height":88,"caption":"DR. Dario Juris"},"image":{"@id":"https:\/\/dariojuris.com\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"design_santiago","author_link":"https:\/\/dariojuris.com\/en\/author\/design_santiago\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/pages\/754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/comments?post=754"}],"version-history":[{"count":7,"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/pages\/754\/revisions"}],"predecessor-version":[{"id":846,"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/pages\/754\/revisions\/846"}],"wp:attachment":[{"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/media?parent=754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}