{"id":636,"date":"2025-07-09T01:24:51","date_gmt":"2025-07-09T06:24:51","guid":{"rendered":"https:\/\/dariojuris.com\/2025\/?post_type=portfolio&#038;p=636"},"modified":"2025-07-11T06:48:39","modified_gmt":"2025-07-11T11:48:39","slug":"lifting-facial-ritidoplastia","status":"publish","type":"portfolio","link":"https:\/\/dariojuris.com\/en\/portfolio-2\/lifting-facial-ritidoplastia\/","title":{"rendered":"Facelift \u2013 Rhytidectomy"},"content":{"rendered":"<style>.kb-row-layout-id636_3bc715-2d > .kt-row-column-wrap{align-content:end;}:where(.kb-row-layout-id636_3bc715-2d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:end;}.kb-row-layout-id636_3bc715-2d > .kt-row-column-wrap{column-gap:0px;row-gap:0px;max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;min-height:400px;grid-template-columns:minmax(0, calc(65% - ((0px * 1 )\/2)))minmax(0, calc(35% - ((0px * 1 )\/2)));}.kb-row-layout-id636_3bc715-2d > .kt-row-layout-overlay{opacity:0.00;mix-blend-mode:multiply;}@media all and (max-width: 1024px){.kb-row-layout-id636_3bc715-2d > .kt-row-column-wrap{padding-top:60px;padding-right:30px;padding-bottom:60px;padding-left:30px;min-height:0px;grid-template-columns:minmax(0, calc(65% - ((0px * 1 )\/2)))minmax(0, calc(35% - ((0px * 1 )\/2)));}}@media all and (max-width: 767px){.kb-row-layout-id636_3bc715-2d > .kt-row-column-wrap{padding-top:50px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id636_3bc715-2d{background:#f2f3f5;}.kb-row-layout-id636_3bc715-2d .kb-blocks-bg-video-container,.kb-row-layout-id636_3bc715-2d .kb-blocks-bg-slider{display:none;}.kb-row-layout-id636_3bc715-2d > .kt-row-layout-overlay{opacity:0.00;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id636_3bc715-2d alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-blocks-carousel kb-blocks-bg-slider kt-carousel-container-dotstyle-dark\"><div class=\"kt-blocks-carousel-init splide kb-blocks-bg-slider-init kt-carousel-arrowstyle-none kt-carousel-dotstyle-dark\" data-slider-anim-speed=\"400\" data-slider-type=\"slider\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\" data-slider-speed=\"7000\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-0\" style=\"background-image:url(https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/Detalle-scaled.webp); background-size:cover; background-position:right center; background-repeat:no-repeat;\"><\/div><\/li><\/ul><\/div><\/div><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-left-golden kt-mobile-layout-row kt-row-valign-bottom kb-theme-content-width\">\n<style>.kadence-column636_58e2c1-17 > .kt-inside-inner-col{display:flex;}.kadence-column636_58e2c1-17 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:50px;padding-left:0px;}.kadence-column636_58e2c1-17 > .kt-inside-inner-col,.kadence-column636_58e2c1-17 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_58e2c1-17 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_58e2c1-17 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column636_58e2c1-17 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column636_58e2c1-17{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_58e2c1-17{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_58e2c1-17 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column636_58e2c1-17 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_58e2c1-17{position:relative;}.kadence-column636_58e2c1-17, .kt-inside-inner-col > .kadence-column636_58e2c1-17:not(.specificity){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}@media all and (max-width: 1024px){.kadence-column636_58e2c1-17 > .kt-inside-inner-col{padding-top:20px;padding-bottom:20px;flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column636_58e2c1-17{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_58e2c1-17{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_58e2c1-17 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kadence-column636_58e2c1-17 > .kt-inside-inner-col{padding-top:0px;padding-right:30px;padding-bottom:0px;padding-left:30px;flex-direction:column;justify-content:flex-end;}.kt-row-column-wrap > .kadence-column636_58e2c1-17{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_58e2c1-17{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_58e2c1-17 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_58e2c1-17\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_8e99d0-a2, .wp-block-kadence-advancedheading.kt-adv-heading636_8e99d0-a2[data-kb-block=\"kb-adv-heading636_8e99d0-a2\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_8e99d0-a2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_8e99d0-a2[data-kb-block=\"kb-adv-heading636_8e99d0-a2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_8e99d0-a2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_8e99d0-a2[data-kb-block=\"kb-adv-heading636_8e99d0-a2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading636_8e99d0-a2, .wp-block-kadence-advancedheading.kt-adv-heading636_8e99d0-a2[data-kb-block=\"kb-adv-heading636_8e99d0-a2\"]{text-align:left!important;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading636_8e99d0-a2, .wp-block-kadence-advancedheading.kt-adv-heading636_8e99d0-a2[data-kb-block=\"kb-adv-heading636_8e99d0-a2\"]{text-align:center!important;}}<\/style>\n<h4 class=\"kt-adv-heading636_8e99d0-a2 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_8e99d0-a2\">Cirug\u00edas Faciales<\/h4>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading636_401b29-60, .wp-block-kadence-advancedheading.kt-adv-heading636_401b29-60[data-kb-block=\"kb-adv-heading636_401b29-60\"]{font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading636_401b29-60 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_401b29-60[data-kb-block=\"kb-adv-heading636_401b29-60\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_401b29-60 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_401b29-60[data-kb-block=\"kb-adv-heading636_401b29-60\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading636_401b29-60, .wp-block-kadence-advancedheading.kt-adv-heading636_401b29-60[data-kb-block=\"kb-adv-heading636_401b29-60\"]{text-align:left!important;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading636_401b29-60, .wp-block-kadence-advancedheading.kt-adv-heading636_401b29-60[data-kb-block=\"kb-adv-heading636_401b29-60\"]{text-align:center!important;}}<\/style>\n<h2 class=\"kt-adv-heading636_401b29-60 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_401b29-60\"><strong><strong>Lifting Facial \u2013 Ritidoplastia<\/strong><br><\/strong><\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column636_63a470-c9 > .kt-inside-inner-col,.kadence-column636_63a470-c9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_63a470-c9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_63a470-c9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_63a470-c9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_63a470-c9 > .kt-inside-inner-col:before{opacity:0.99;}.kadence-column636_63a470-c9{position:relative;}@media all and (max-width: 1024px){.kadence-column636_63a470-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_63a470-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_63a470-c9 kvs-lg-false kvs-md-false\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id636_555aa9-55 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id636_555aa9-55 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id636_555aa9-55 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:975px;margin-left:auto;margin-right:auto;padding-top:80px;padding-bottom:45px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id636_555aa9-55 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id636_555aa9-55 > .kt-row-column-wrap{padding-top:60px;padding-right:50px;padding-bottom:60px;padding-left:50px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id636_555aa9-55 > .kt-row-column-wrap{padding-top:50px;padding-right:30px;padding-bottom:50px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id636_555aa9-55 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column636_d79b01-5c > .kt-inside-inner-col,.kadence-column636_d79b01-5c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_d79b01-5c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_d79b01-5c > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_d79b01-5c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_d79b01-5c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_d79b01-5c{position:relative;}@media all and (max-width: 1024px){.kadence-column636_d79b01-5c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_d79b01-5c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_d79b01-5c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_a9e563-e1, .wp-block-kadence-advancedheading.kt-adv-heading636_a9e563-e1[data-kb-block=\"kb-adv-heading636_a9e563-e1\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_a9e563-e1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_a9e563-e1[data-kb-block=\"kb-adv-heading636_a9e563-e1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_a9e563-e1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_a9e563-e1[data-kb-block=\"kb-adv-heading636_a9e563-e1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading636_a9e563-e1 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_a9e563-e1\">El paso de los a\u00f1os produce arrugas y ca\u00edda de la piel de la cara que se acompa\u00f1a de flacidez muscular del rostro, cambiando la expresi\u00f3n y acentuando pliegues caracter\u00edsticos del envejecimiento.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns636_042c5b-ff{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns636_042c5b-ff .kt-button{font-weight:normal;font-style:normal;}.kt-btns636_042c5b-ff .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns636_042c5b-ff .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns636_042c5b-ff .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns636_042c5b-ff .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns636_042c5b-ff .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns636_042c5b-ff .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns636_042c5b-ff .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns636_042c5b-ff\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn636_59c3d1-4a.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn636_59c3d1-4a.kb-button{border-top-left-radius:40px;border-top-right-radius:40px;border-bottom-right-radius:40px;border-bottom-left-radius:40px;padding-top:25px;padding-right:25px;padding-bottom:25px;padding-left:25px;}<\/style><a class=\"kb-button kt-button button kb-btn636_59c3d1-4a kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"#FAQ\"><span class=\"kt-btn-inner-text\">Preguntas Frecuentes<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap{column-gap:80px;row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:45px;padding-bottom:40px;grid-template-columns:minmax(0, calc(45% - ((80px * 1 )\/2)))minmax(0, calc(55% - ((80px * 1 )\/2)));}.kb-row-layout-id636_d67d55-b2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap{padding-top:0px;padding-right:50px;padding-bottom:60px;padding-left:50px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}}@media all and (max-width: 1024px){.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}}@media all and (max-width: 1024px){.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}}@media all and (max-width: 1024px){.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}}@media all and (max-width: 1024px){.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}}@media all and (max-width: 1024px){.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}}@media all and (max-width: 1024px){.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}}@media all and (max-width: 1024px){.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}@media all and (max-width: 767px){.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id636_d67d55-b2{margin-top:0px;}.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap{padding-top:0px;padding-right:30px;padding-bottom:50px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id636_d67d55-b2 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id636_d67d55-b2 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column636_077467-8d > .kt-inside-inner-col,.kadence-column636_077467-8d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_077467-8d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_077467-8d > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_077467-8d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_077467-8d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_077467-8d{position:relative;}@media all and (max-width: 1024px){.kadence-column636_077467-8d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_077467-8d > .kt-inside-inner-col{padding-top:20px;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_077467-8d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_dd88d6-25, .wp-block-kadence-advancedheading.kt-adv-heading636_dd88d6-25[data-kb-block=\"kb-adv-heading636_dd88d6-25\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_dd88d6-25 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_dd88d6-25[data-kb-block=\"kb-adv-heading636_dd88d6-25\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_dd88d6-25 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_dd88d6-25[data-kb-block=\"kb-adv-heading636_dd88d6-25\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading636_dd88d6-25, .wp-block-kadence-advancedheading.kt-adv-heading636_dd88d6-25[data-kb-block=\"kb-adv-heading636_dd88d6-25\"]{text-align:left!important;}}<\/style>\n<h3 class=\"kt-adv-heading636_dd88d6-25 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_dd88d6-25\">Ventajas del procedimiento<\/h3>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box636_7ac897-c7 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box636_7ac897-c7 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#ffffff;padding-top:0px;padding-right:0px;padding-bottom:20px;padding-left:0px;}.kt-info-box636_7ac897-c7.wp-block-kadence-infobox{max-width:100%;}.kt-info-box636_7ac897-c7 .kadence-info-box-image-inner-intrisic-container{max-width:46px;}.kt-info-box636_7ac897-c7 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:128px;height:0px;max-width:100%;}.kt-info-box636_7ac897-c7 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box636_7ac897-c7 .kt-info-svg-icon-flip, .kt-info-box636_7ac897-c7 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box636_7ac897-c7 .kt-blocks-info-box-media{color:var(--global-palette3, #1A202C);background:var(--global-palette8, #F7FAFC);border-radius:10px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:7px;padding-right:7px;padding-bottom:7px;padding-left:7px;margin-top:0px;margin-right:30px;margin-bottom:0px;margin-left:0px;}.kt-info-box636_7ac897-c7 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:10px;}.kt-info-box636_7ac897-c7 .kt-infobox-textcontent h4.kt-blocks-info-box-title{text-transform:none;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:7px;margin-left:0px;}.kt-info-box636_7ac897-c7 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box636_7ac897-c7 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box636_7ac897-c7 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box636_7ac897-c7 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box636_7ac897-c7\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/Iconos-1.webp\" alt=\"\" width=\"128\" height=\"128\" class=\"kt-info-box-image wp-image-422\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\"><strong>Rejuvenecimiento facial visible y natural<\/strong><\/h4><p class=\"kt-blocks-info-box-text\">Elimina arrugas y flacidez, devolviendo firmeza y frescura sin alterar la expresi\u00f3n natural del rostro.<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box636_437c70-1d .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box636_437c70-1d .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#ffffff;padding-top:0px;padding-right:0px;padding-bottom:20px;padding-left:0px;}.kt-info-box636_437c70-1d.wp-block-kadence-infobox{max-width:100%;}.kt-info-box636_437c70-1d .kadence-info-box-image-inner-intrisic-container{max-width:46px;}.kt-info-box636_437c70-1d .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:128px;height:0px;max-width:100%;}.kt-info-box636_437c70-1d .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box636_437c70-1d .kt-info-svg-icon-flip, .kt-info-box636_437c70-1d .kt-blocks-info-box-number{font-size:50px;}.kt-info-box636_437c70-1d .kt-blocks-info-box-media{color:var(--global-palette3, #1A202C);background:#bac7c8;border-radius:10px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:7px;padding-right:7px;padding-bottom:7px;padding-left:7px;margin-top:0px;margin-right:30px;margin-bottom:0px;margin-left:0px;}.kt-info-box636_437c70-1d .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:10px;}.kt-info-box636_437c70-1d .kt-infobox-textcontent h4.kt-blocks-info-box-title{text-transform:none;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:7px;margin-left:0px;}.kt-info-box636_437c70-1d .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box636_437c70-1d .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box636_437c70-1d .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box636_437c70-1d .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box636_437c70-1d\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/Iconos-5.webp\" alt=\"\" width=\"128\" height=\"128\" class=\"kt-info-box-image wp-image-427\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\"><strong>Definici\u00f3n de contornos faciales<\/strong><\/h4><p class=\"kt-blocks-info-box-text\">Mejora la l\u00ednea mandibular, el cuello y las mejillas, recuperando una apariencia m\u00e1s arm\u00f3nica y joven.<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box636_d87697-6a .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box636_d87697-6a .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#ffffff;padding-top:0px;padding-right:0px;padding-bottom:20px;padding-left:0px;}.kt-info-box636_d87697-6a.wp-block-kadence-infobox{max-width:100%;}.kt-info-box636_d87697-6a .kadence-info-box-image-inner-intrisic-container{max-width:46px;}.kt-info-box636_d87697-6a .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:128px;height:0px;max-width:100%;}.kt-info-box636_d87697-6a .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box636_d87697-6a .kt-info-svg-icon-flip, .kt-info-box636_d87697-6a .kt-blocks-info-box-number{font-size:50px;}.kt-info-box636_d87697-6a .kt-blocks-info-box-media{color:var(--global-palette3, #1A202C);background:var(--global-palette8, #F7FAFC);border-radius:10px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:7px;padding-right:7px;padding-bottom:7px;padding-left:7px;margin-top:0px;margin-right:30px;margin-bottom:0px;margin-left:0px;}.kt-info-box636_d87697-6a .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:10px;}.kt-info-box636_d87697-6a .kt-infobox-textcontent h4.kt-blocks-info-box-title{text-transform:none;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:7px;margin-left:0px;}.kt-info-box636_d87697-6a .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box636_d87697-6a .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box636_d87697-6a .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box636_d87697-6a .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box636_d87697-6a\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/Iconos-4.webp\" alt=\"\" width=\"128\" height=\"128\" class=\"kt-info-box-image wp-image-426\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\"><strong>Resultados duraderos<\/strong><\/h4><p class=\"kt-blocks-info-box-text\">A diferencia de tratamientos no invasivos, sus efectos pueden durar varios a\u00f1os con el cuidado adecuado.<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box636_112b9f-ef .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box636_112b9f-ef .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#ffffff;padding-top:0px;padding-right:0px;padding-bottom:20px;padding-left:0px;}.kt-info-box636_112b9f-ef.wp-block-kadence-infobox{max-width:100%;}.kt-info-box636_112b9f-ef .kadence-info-box-image-inner-intrisic-container{max-width:46px;}.kt-info-box636_112b9f-ef .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:128px;height:0px;max-width:100%;}.kt-info-box636_112b9f-ef .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box636_112b9f-ef .kt-info-svg-icon-flip, .kt-info-box636_112b9f-ef .kt-blocks-info-box-number{font-size:50px;}.kt-info-box636_112b9f-ef .kt-blocks-info-box-media{color:var(--global-palette3, #1A202C);background:#bac7c8;border-radius:10px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:7px;padding-right:7px;padding-bottom:7px;padding-left:7px;margin-top:0px;margin-right:30px;margin-bottom:0px;margin-left:0px;}.kt-info-box636_112b9f-ef .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:10px;}.kt-info-box636_112b9f-ef .kt-infobox-textcontent h4.kt-blocks-info-box-title{text-transform:none;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:7px;margin-left:0px;}.kt-info-box636_112b9f-ef .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box636_112b9f-ef .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box636_112b9f-ef .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box636_112b9f-ef .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box636_112b9f-ef\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/Iconos-3.webp\" alt=\"\" width=\"128\" height=\"128\" class=\"kt-info-box-image wp-image-425\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\"><strong>Mejora la autoestima<\/strong><\/h4><p class=\"kt-blocks-info-box-text\">Al mejorar la apariencia facial, muchas personas experimentan una mayor seguridad y bienestar emocional.<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box636_b6cf7a-ad .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box636_b6cf7a-ad .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#ffffff;padding-top:0px;padding-right:0px;padding-bottom:20px;padding-left:0px;}.kt-info-box636_b6cf7a-ad.wp-block-kadence-infobox{max-width:100%;}.kt-info-box636_b6cf7a-ad .kadence-info-box-image-inner-intrisic-container{max-width:46px;}.kt-info-box636_b6cf7a-ad .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:128px;height:0px;max-width:100%;}.kt-info-box636_b6cf7a-ad .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box636_b6cf7a-ad .kt-info-svg-icon-flip, .kt-info-box636_b6cf7a-ad .kt-blocks-info-box-number{font-size:50px;}.kt-info-box636_b6cf7a-ad .kt-blocks-info-box-media{color:var(--global-palette3, #1A202C);background:var(--global-palette8, #F7FAFC);border-radius:10px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:7px;padding-right:7px;padding-bottom:7px;padding-left:7px;margin-top:0px;margin-right:30px;margin-bottom:0px;margin-left:0px;}.kt-info-box636_b6cf7a-ad .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:10px;}.kt-info-box636_b6cf7a-ad .kt-infobox-textcontent h4.kt-blocks-info-box-title{text-transform:none;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:7px;margin-left:0px;}.kt-info-box636_b6cf7a-ad .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box636_b6cf7a-ad .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box636_b6cf7a-ad .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);text-align:left;display:flex;justify-content:flex-start;flex-direction:row;}.kt-info-box636_b6cf7a-ad .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box636_b6cf7a-ad\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top kb-info-mobile-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/Iconos-2.webp\" alt=\"\" width=\"128\" height=\"128\" class=\"kt-info-box-image wp-image-424\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\"><strong>Procedimiento personalizable<\/strong><\/h4><p class=\"kt-blocks-info-box-text\">Puede combinarse con otros tratamientos como blefaroplastia o rellenos para un resultado integral.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column636_9dac14-06 > .kt-inside-inner-col,.kadence-column636_9dac14-06 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_9dac14-06 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_9dac14-06 > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_9dac14-06 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_9dac14-06 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_9dac14-06{position:relative;}@media all and (max-width: 1024px){.kadence-column636_9dac14-06 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_9dac14-06 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_9dac14-06\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id636_7c4a12-1f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id636_7c4a12-1f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id636_7c4a12-1f > .kt-row-column-wrap{column-gap:30px;row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id636_7c4a12-1f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id636_7c4a12-1f > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id636_7c4a12-1f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id636_7c4a12-1f alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column636_61b5a0-9b > .kt-inside-inner-col,.kadence-column636_61b5a0-9b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_61b5a0-9b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_61b5a0-9b > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_61b5a0-9b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_61b5a0-9b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_61b5a0-9b{position:relative;}@media all and (max-width: 1024px){.kadence-column636_61b5a0-9b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_61b5a0-9b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_61b5a0-9b\"><div class=\"kt-inside-inner-col\"><style>.kadence-video-popup636_bd8680-e9 .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}.kadence-video-popup636_bd8680-e9 .kadence-video-popup-wrap .kt-video-svg-icon{color:var(--global-palette9, #ffffff);}.kadence-video-popup636_bd8680-e9 .kadence-video-popup-wrap .kt-video-svg-icon{font-size:20px;}.kadence-video-popup636_bd8680-e9 .kadence-video-popup-wrap .kt-video-svg-icon > svg{stroke-width:2;}.kadence-video-popup636_bd8680-e9 .kadence-video-popup-wrap:hover .kt-video-svg-icon{color:var(--global-palette1, #3182CE);}.kadence-video-popup636_bd8680-e9 .kadence-video-popup-wrap .kt-video-svg-icon.kt-video-svg-icon-style-stacked{background:rgba(255, 255, 255, 0.51);padding:11px;}.kadence-video-popup636_bd8680-e9 .kadence-video-popup-wrap .kadence-video-overlay{opacity:0.3;;mix-blend-mode:none;;background:rgba(0, 0, 0, 0.32);;}.kadence-video-popup636_bd8680-e9 .kadence-video-popup-wrap:hover .kadence-video-overlay{opacity:0.5;;}.glightbox-kadence-dark.kadence-popup-636_bd8680-e9 .goverlay{background:#000000;opacity:0.85;}.glightbox-container.kadence-popup-636_bd8680-e9 .gclose path, .glightbox-container.kadence-popup-636_bd8680-e9 .gnext path, .glightbox-container.kadence-popup-636_bd8680-e9 .gprev path{fill:#ffffff;}.glightbox-container.kadence-popup-636_bd8680-e9 .gslide-video, .glightbox-container.kadence-popup-636_bd8680-e9 .gvideo-local{max-width:900px !important;}@media all and (max-width: 1024px){.kadence-video-popup636_bd8680-e9 .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;}}@media all and (max-width: 767px){.kadence-video-popup636_bd8680-e9 .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-videopopup kadence-video-popup636_bd8680-e9\"><div class=\"kadence-video-popup-wrap kadence-video-noshadow\"><div class=\"kadence-video-intrinsic  kadence-video-set-ratio-200\" style=\"padding-bottom:200%\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_7149-scaled.webp\" alt=\"\" width=\"1920\" height=\"2560\" class=\"kadence-video-poster wp-image-645\" srcset=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_7149-scaled.webp 1920w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_7149-225x300.webp 225w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_7149-768x1024.webp 768w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_7149-1152x1536.webp 1152w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_7149-1536x2048.webp 1536w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_7149-500x667.webp 500w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_7149-800x1067.webp 800w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_7149-1280x1707.webp 1280w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><div class=\"kadence-video-overlay\"><\/div><a class=\"kadence-video-popup-link kadence-video-type-external\" href=\"https:\/\/youtu.be\/F-VceDHGx7M\" role=\"button\" data-popup-class=\"kadence-popup-636_bd8680-e9\" data-effect=\"none\" data-popup-id=\"kadence-local-video-636_bd8680-e9\" data-popup-auto=\"true\" data-youtube-cookies=\"true\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_play kt-video-svg-icon kt-video-svg-icon-style-stacked kt-video-svg-icon-ic play kt-video-play-animation-none kt-video-svg-icon-size-20\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Play<\/title><path d=\"M0 0v6l6-3-6-3z\" transform=\"translate(1 1)\"\/><\/svg><\/span><\/a><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column636_7253f8-17 > .kt-inside-inner-col{display:flex;}.kadence-column636_7253f8-17 > .kt-inside-inner-col,.kadence-column636_7253f8-17 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_7253f8-17 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_7253f8-17 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column636_7253f8-17 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column636_7253f8-17{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_7253f8-17{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_7253f8-17 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column636_7253f8-17 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_7253f8-17{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column636_7253f8-17{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_7253f8-17{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_7253f8-17 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column636_7253f8-17 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column636_7253f8-17{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_7253f8-17{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_7253f8-17 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column636_7253f8-17 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_7253f8-17\"><div class=\"kt-inside-inner-col\"><style>.kb-image636_56dd03-30 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}.kb-image636_56dd03-30 img.kb-img, .kb-image636_56dd03-30 .kb-img img{border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image636_56dd03-30 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-port23\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_8299-scaled.webp\" alt=\"\" class=\"kb-img wp-image-644\" srcset=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_8299-scaled.webp 1920w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_8299-225x300.webp 225w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_8299-768x1024.webp 768w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_8299-1152x1536.webp 1152w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_8299-1536x2048.webp 1536w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_8299-500x667.webp 500w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_8299-800x1067.webp 800w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/IMG_8299-1280x1707.webp 1280w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><\/figure>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns636_dd03e9-7b{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns636_dd03e9-7b .kt-button{font-weight:normal;font-style:normal;}.kt-btns636_dd03e9-7b .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns636_dd03e9-7b .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns636_dd03e9-7b .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns636_dd03e9-7b .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns636_dd03e9-7b .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns636_dd03e9-7b .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns636_dd03e9-7b .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns636_dd03e9-7b\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn636_b92e9b-3b.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn636_b92e9b-3b.kb-button{border-top-left-radius:40px;border-top-right-radius:40px;border-bottom-right-radius:40px;border-bottom-left-radius:40px;padding-top:25px;padding-right:25px;padding-bottom:25px;padding-left:25px;}<\/style><span class=\"kb-button kt-button button kb-btn636_b92e9b-3b kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Agenta tu cita<\/span><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id636_bf07e1-cd > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id636_bf07e1-cd > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id636_bf07e1-cd > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:40px;padding-bottom:60px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id636_bf07e1-cd > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id636_bf07e1-cd > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id636_bf07e1-cd > .kt-row-column-wrap{padding-top:50px;padding-right:30px;padding-bottom:50px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id636_bf07e1-cd alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column636_cac70f-ab > .kt-inside-inner-col,.kadence-column636_cac70f-ab > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_cac70f-ab > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_cac70f-ab > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_cac70f-ab > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_cac70f-ab > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_cac70f-ab{position:relative;}@media all and (max-width: 1024px){.kadence-column636_cac70f-ab > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_cac70f-ab > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_cac70f-ab\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_259607-d7, .wp-block-kadence-advancedheading.kt-adv-heading636_259607-d7[data-kb-block=\"kb-adv-heading636_259607-d7\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_259607-d7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_259607-d7[data-kb-block=\"kb-adv-heading636_259607-d7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_259607-d7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_259607-d7[data-kb-block=\"kb-adv-heading636_259607-d7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading636_259607-d7 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_259607-d7\">Nuestros resultados<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading636_82e0fa-3f, .wp-block-kadence-advancedheading.kt-adv-heading636_82e0fa-3f[data-kb-block=\"kb-adv-heading636_82e0fa-3f\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_82e0fa-3f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_82e0fa-3f[data-kb-block=\"kb-adv-heading636_82e0fa-3f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_82e0fa-3f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_82e0fa-3f[data-kb-block=\"kb-adv-heading636_82e0fa-3f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading636_82e0fa-3f wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_82e0fa-3f\">Antes y despu\u00e9s<\/h6>\n\n\n<style>.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-636_8119ce-00{overflow:hidden;}.kb-gallery-id-636_8119ce-00 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-636_8119ce-00 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-wrap-id-636_8119ce-00.wp-block-kadence-advancedgallery{overflow:visible;}.kb-gallery-wrap-id-636_8119ce-00.wp-block-kadence-advancedgallery .kt-blocks-carousel{overflow:visible;}<\/style><div class=\"kb-gallery-wrap-id-636_8119ce-00 alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-carousel kb-gallery-id-636_8119ce-00 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel splide kt-carousel-container-dotstyle-none kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-none kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"2\" data-columns-xl=\"2\" data-columns-md=\"2\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-auto=\"\" data-slider-speed=\"7000\" data-slider-gap=\"20px\" data-slider-gap-tablet=\"20px\" data-slider-gap-mobile=\"20px\" data-show-pause-button=\"false\" data-slider-label=\"Photo Gallery Carousel\"><div class=\"splide__track\"><ul class=\"kt-blocks-carousel-init kb-gallery-carousel splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/fac-01-686e128b12d06.webp\" width=\"555\" height=\"415\" alt=\"\" data-full-image=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/fac-01-686e128b12d06.webp\" data-light-image=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/fac-01-686e128b12d06.webp\" data-id=\"638\" class=\"wp-image-638 skip-lazy\" srcset=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/fac-01-686e128b12d06.webp 555w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/fac-01-686e128b12d06-300x224.webp 300w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/fac-01-686e128b12d06-500x374.webp 500w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/facd-01-686e128b15f4d.webp\" width=\"555\" height=\"415\" alt=\"\" data-full-image=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/facd-01-686e128b15f4d.webp\" data-light-image=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/facd-01-686e128b15f4d.webp\" data-id=\"639\" class=\"wp-image-639 skip-lazy\" srcset=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/facd-01-686e128b15f4d.webp 555w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/facd-01-686e128b15f4d-300x224.webp 300w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/facd-01-686e128b15f4d-500x374.webp 500w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-inherit kb-has-image-ratio-inherit\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/facs-01-686e128c5f8f7.webp\" width=\"555\" height=\"415\" alt=\"\" data-full-image=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/facs-01-686e128c5f8f7.webp\" data-light-image=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/facs-01-686e128c5f8f7.webp\" data-id=\"640\" class=\"wp-image-640 skip-lazy\" srcset=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/facs-01-686e128c5f8f7.webp 555w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/facs-01-686e128c5f8f7-300x224.webp 300w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/facs-01-686e128c5f8f7-500x374.webp 500w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id636_c301d3-8a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id636_c301d3-8a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id636_c301d3-8a > .kt-row-column-wrap{column-gap:60px;row-gap:0px;max-width:1100px;margin-left:auto;margin-right:auto;padding-top:80px;padding-bottom:80px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id636_c301d3-8a{background-color:#ededed;}.kb-row-layout-id636_c301d3-8a > .kt-row-layout-overlay{opacity:1;}@media all and (max-width: 1024px){.kb-row-layout-id636_c301d3-8a > .kt-row-column-wrap{padding-top:60px;padding-right:50px;padding-bottom:400px;padding-left:50px;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id636_c301d3-8a > .kt-row-column-wrap{padding-top:50px;padding-right:30px;padding-bottom:50px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id636_c301d3-8a > .kt-row-layout-overlay{opacity:0.00;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id636_c301d3-8a alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column636_c5c259-93 > .kt-inside-inner-col{display:flex;}.kadence-column636_c5c259-93 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column636_c5c259-93 > .kt-inside-inner-col,.kadence-column636_c5c259-93 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_c5c259-93 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_c5c259-93 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column636_c5c259-93 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column636_c5c259-93{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_c5c259-93{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_c5c259-93 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column636_c5c259-93 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_c5c259-93{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column636_c5c259-93{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_c5c259-93{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_c5c259-93 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column636_c5c259-93 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column636_c5c259-93{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_c5c259-93{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_c5c259-93 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column636_c5c259-93 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_c5c259-93\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_18535e-7c, .wp-block-kadence-advancedheading.kt-adv-heading636_18535e-7c[data-kb-block=\"kb-adv-heading636_18535e-7c\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_18535e-7c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_18535e-7c[data-kb-block=\"kb-adv-heading636_18535e-7c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_18535e-7c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_18535e-7c[data-kb-block=\"kb-adv-heading636_18535e-7c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading636_18535e-7c, .wp-block-kadence-advancedheading.kt-adv-heading636_18535e-7c[data-kb-block=\"kb-adv-heading636_18535e-7c\"]{text-align:center!important;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading636_18535e-7c, .wp-block-kadence-advancedheading.kt-adv-heading636_18535e-7c[data-kb-block=\"kb-adv-heading636_18535e-7c\"]{padding-bottom:30px;}}<\/style>\n<h2 class=\"kt-adv-heading636_18535e-7c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_18535e-7c\">Paso a Paso del Procedimiento<\/h2>\n\n\n<style>.kb-row-layout-id636_6bd596-11 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id636_6bd596-11 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id636_6bd596-11 > .kt-row-column-wrap{column-gap:20px;row-gap:20px;padding-top:0px;padding-bottom:0px;}.kb-row-layout-id636_6bd596-11 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id636_6bd596-11 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id636_6bd596-11 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id636_6bd596-11 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id636_6bd596-11 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id636_6bd596-11 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id636_6bd596-11 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id636_6bd596-11 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column636_3e2f37-da > .kt-inside-inner-col{padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;}.kadence-column636_3e2f37-da > .kt-inside-inner-col,.kadence-column636_3e2f37-da > .kt-inside-inner-col:before{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kadence-column636_3e2f37-da > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_3e2f37-da > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_3e2f37-da > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_3e2f37-da > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column636_3e2f37-da > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_3e2f37-da{position:relative;}@media all and (max-width: 1024px){.kadence-column636_3e2f37-da > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_3e2f37-da > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_3e2f37-da\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_eda155-d3, .wp-block-kadence-advancedheading.kt-adv-heading636_eda155-d3[data-kb-block=\"kb-adv-heading636_eda155-d3\"]{padding-bottom:0px;margin-bottom:0px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_eda155-d3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_eda155-d3[data-kb-block=\"kb-adv-heading636_eda155-d3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_eda155-d3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_eda155-d3[data-kb-block=\"kb-adv-heading636_eda155-d3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading636_eda155-d3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_eda155-d3\">Paso 1<\/h6>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box636_92aa16-15 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box636_92aa16-15 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:0px;}.kt-info-box636_92aa16-15.wp-block-kadence-infobox{max-width:100%;}.kt-info-box636_92aa16-15 .kadence-info-box-image-inner-intrisic-container{max-width:45px;}.kt-info-box636_92aa16-15 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:128px;height:0px;max-width:100%;}.kt-info-box636_92aa16-15 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box636_92aa16-15 .kt-info-svg-icon-flip, .kt-info-box636_92aa16-15 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box636_92aa16-15 .kt-blocks-info-box-media{background:var(--global-palette8, #F7FAFC);border-radius:10px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:7px;padding-right:7px;padding-bottom:7px;padding-left:7px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box636_92aa16-15 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:10px;}.kt-info-box636_92aa16-15 .kt-infobox-textcontent h6.kt-blocks-info-box-title{margin-top:0px;margin-right:0px;margin-bottom:1px;margin-left:0px;}.kt-info-box636_92aa16-15 h6.kt-blocks-info-box-title{min-height:0px;}.kt-info-box636_92aa16-15 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box636_92aa16-15\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/5b7ce52a155fd359431b617829da01b9ec1b1097-686622bc94149.webp\" alt=\"\" width=\"128\" height=\"128\" class=\"kt-info-box-image wp-image-444\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h6 class=\"kt-blocks-info-box-title\"><strong>Valoraci\u00f3n personalizada y planificaci\u00f3n quir\u00fargica<\/strong><\/h6><p class=\"kt-blocks-info-box-text\">En la consulta, el cirujano analiza la estructura facial, calidad de la piel y grado de flacidez. Se define si se usar\u00e1 anestesia general o local con sedaci\u00f3n, y se explica el alcance real del procedimiento.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column636_267608-b2 > .kt-inside-inner-col{padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;}.kadence-column636_267608-b2 > .kt-inside-inner-col,.kadence-column636_267608-b2 > .kt-inside-inner-col:before{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kadence-column636_267608-b2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_267608-b2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_267608-b2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_267608-b2 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column636_267608-b2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_267608-b2{position:relative;}@media all and (max-width: 1024px){.kadence-column636_267608-b2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_267608-b2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_267608-b2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_3221e9-d1, .wp-block-kadence-advancedheading.kt-adv-heading636_3221e9-d1[data-kb-block=\"kb-adv-heading636_3221e9-d1\"]{padding-bottom:0px;margin-bottom:0px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_3221e9-d1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_3221e9-d1[data-kb-block=\"kb-adv-heading636_3221e9-d1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_3221e9-d1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_3221e9-d1[data-kb-block=\"kb-adv-heading636_3221e9-d1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading636_3221e9-d1 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_3221e9-d1\">Paso 2<\/h6>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box636_8b6645-80 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box636_8b6645-80 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:0px;}.kt-info-box636_8b6645-80.wp-block-kadence-infobox{max-width:100%;}.kt-info-box636_8b6645-80 .kadence-info-box-image-inner-intrisic-container{max-width:45px;}.kt-info-box636_8b6645-80 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:128px;height:0px;max-width:100%;}.kt-info-box636_8b6645-80 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box636_8b6645-80 .kt-info-svg-icon-flip, .kt-info-box636_8b6645-80 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box636_8b6645-80 .kt-blocks-info-box-media{background:#bac7c8;border-radius:10px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:7px;padding-right:7px;padding-bottom:7px;padding-left:7px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box636_8b6645-80 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:10px;}.kt-info-box636_8b6645-80 .kt-infobox-textcontent h6.kt-blocks-info-box-title{margin-top:0px;margin-right:0px;margin-bottom:1px;margin-left:0px;}.kt-info-box636_8b6645-80 h6.kt-blocks-info-box-title{min-height:0px;}.kt-info-box636_8b6645-80 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box636_8b6645-80\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/90352149487be5bb8c59f425d76ffc55eb2b329d-686622bcf2f43.webp\" alt=\"\" width=\"128\" height=\"128\" class=\"kt-info-box-image wp-image-445\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h6 class=\"kt-blocks-info-box-title\"><strong>Procedimiento quir\u00fargico<\/strong><\/h6><p class=\"kt-blocks-info-box-text\">Se realizan incisiones estrat\u00e9gicas en zonas poco visibles (como detr\u00e1s de las orejas o l\u00ednea del cabello). Se reposicionan los m\u00fasculos, se retira el exceso de piel y se tensan los tejidos faciales para devolver firmeza.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column636_8e3c60-38 > .kt-inside-inner-col{padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;}.kadence-column636_8e3c60-38 > .kt-inside-inner-col,.kadence-column636_8e3c60-38 > .kt-inside-inner-col:before{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kadence-column636_8e3c60-38 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_8e3c60-38 > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_8e3c60-38 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_8e3c60-38 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column636_8e3c60-38 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_8e3c60-38{position:relative;}@media all and (max-width: 1024px){.kadence-column636_8e3c60-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_8e3c60-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_8e3c60-38\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_0ab526-7c, .wp-block-kadence-advancedheading.kt-adv-heading636_0ab526-7c[data-kb-block=\"kb-adv-heading636_0ab526-7c\"]{padding-bottom:0px;margin-bottom:0px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_0ab526-7c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_0ab526-7c[data-kb-block=\"kb-adv-heading636_0ab526-7c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_0ab526-7c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_0ab526-7c[data-kb-block=\"kb-adv-heading636_0ab526-7c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading636_0ab526-7c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_0ab526-7c\">Paso 3<\/h6>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box636_5ef67e-8d .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box636_5ef67e-8d .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:0px;}.kt-info-box636_5ef67e-8d.wp-block-kadence-infobox{max-width:100%;}.kt-info-box636_5ef67e-8d .kadence-info-box-image-inner-intrisic-container{max-width:45px;}.kt-info-box636_5ef67e-8d .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:128px;height:0px;max-width:100%;}.kt-info-box636_5ef67e-8d .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box636_5ef67e-8d .kt-info-svg-icon-flip, .kt-info-box636_5ef67e-8d .kt-blocks-info-box-number{font-size:50px;}.kt-info-box636_5ef67e-8d .kt-blocks-info-box-media{background:var(--global-palette8, #F7FAFC);border-radius:10px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:7px;padding-right:7px;padding-bottom:7px;padding-left:7px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box636_5ef67e-8d .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:10px;}.kt-info-box636_5ef67e-8d .kt-infobox-textcontent h6.kt-blocks-info-box-title{margin-top:0px;margin-right:0px;margin-bottom:1px;margin-left:0px;}.kt-info-box636_5ef67e-8d h6.kt-blocks-info-box-title{min-height:0px;}.kt-info-box636_5ef67e-8d .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box636_5ef67e-8d\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/645a8c217f369e79f39d0f57d1921e21ad4e646b-686622bc9414a.webp\" alt=\"\" width=\"128\" height=\"128\" class=\"kt-info-box-image wp-image-446\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h6 class=\"kt-blocks-info-box-title\"><strong>Recuperaci\u00f3n postoperatoria<\/strong><\/h6><p class=\"kt-blocks-info-box-text\">Se colocan ap\u00f3sitos o drenajes temporales. El paciente recibe instrucciones precisas sobre el cuidado de las heridas y control del edema. En pocos d\u00edas puede retomar actividades suaves, y en semanas se ven los resultados completos.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column636_7147e2-38 > .kt-inside-inner-col,.kadence-column636_7147e2-38 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_7147e2-38 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_7147e2-38 > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_7147e2-38 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_7147e2-38 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_7147e2-38{position:relative;}@media all and (max-width: 1024px){.kadence-column636_7147e2-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_7147e2-38 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_7147e2-38 kvs-md-false kvs-sm-false\"><div class=\"kt-inside-inner-col\"><style>.kb-image636_0309c3-20 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image636_0309c3-20 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"713\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/dentist-doing-check-up-patient-1-686623586d9b2.webp\" alt=\"\" class=\"kb-img wp-image-443\" srcset=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/dentist-doing-check-up-patient-1-686623586d9b2.webp 550w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/dentist-doing-check-up-patient-1-686623586d9b2-231x300.webp 231w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id636_ad5973-04 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id636_ad5973-04 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id636_ad5973-04 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:80px;padding-bottom:80px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id636_ad5973-04 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id636_ad5973-04 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id636_ad5973-04 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id636_ad5973-04 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column636_3ad04a-b0 > .kt-inside-inner-col,.kadence-column636_3ad04a-b0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_3ad04a-b0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_3ad04a-b0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_3ad04a-b0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_3ad04a-b0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_3ad04a-b0{position:relative;}@media all and (max-width: 1024px){.kadence-column636_3ad04a-b0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_3ad04a-b0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_3ad04a-b0\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_b118ae-64, .wp-block-kadence-advancedheading.kt-adv-heading636_b118ae-64[data-kb-block=\"kb-adv-heading636_b118ae-64\"]{max-width:800px;margin-right:auto;margin-left:auto;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_b118ae-64 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_b118ae-64[data-kb-block=\"kb-adv-heading636_b118ae-64\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_b118ae-64 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_b118ae-64[data-kb-block=\"kb-adv-heading636_b118ae-64\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading636_b118ae-64 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_b118ae-64\">Cuidados Pre &#8211; Post Quir\u00fargicos de <strong><strong>Lifting Facial \u2013 Ritidoplastia<\/strong><br><\/strong><\/h2>\n\n\n<style>.kb-row-layout-id636_35c08a-17 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id636_35c08a-17 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id636_35c08a-17 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:40px;padding-bottom:24px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id636_35c08a-17 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id636_35c08a-17 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id636_35c08a-17 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id636_35c08a-17 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column636_4af848-3c > .kt-inside-inner-col,.kadence-column636_4af848-3c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_4af848-3c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_4af848-3c > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_4af848-3c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_4af848-3c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_4af848-3c{position:relative;}@media all and (max-width: 1024px){.kadence-column636_4af848-3c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_4af848-3c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_4af848-3c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_7d0de8-1d, .wp-block-kadence-advancedheading.kt-adv-heading636_7d0de8-1d[data-kb-block=\"kb-adv-heading636_7d0de8-1d\"]{font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading636_7d0de8-1d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_7d0de8-1d[data-kb-block=\"kb-adv-heading636_7d0de8-1d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_7d0de8-1d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_7d0de8-1d[data-kb-block=\"kb-adv-heading636_7d0de8-1d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading636_7d0de8-1d wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_7d0de8-1d\">Antes del procedimiento<\/h4>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading636_4d4f0e-29, .wp-block-kadence-advancedheading.kt-adv-heading636_4d4f0e-29[data-kb-block=\"kb-adv-heading636_4d4f0e-29\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_4d4f0e-29 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_4d4f0e-29[data-kb-block=\"kb-adv-heading636_4d4f0e-29\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_4d4f0e-29 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_4d4f0e-29[data-kb-block=\"kb-adv-heading636_4d4f0e-29\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading636_4d4f0e-29 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_4d4f0e-29\">Suspende el consumo de tabaco, alcohol, aspirina, antiinflamatorios y vitamina E al menos una semana antes. Realiza todos los ex\u00e1menes preoperatorios indicados y aseg\u00farate de discutir tus expectativas con el cirujano. Llega al procedimiento en ayunas y sin maquillaje ni joyas.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading636_101025-d7, .wp-block-kadence-advancedheading.kt-adv-heading636_101025-d7[data-kb-block=\"kb-adv-heading636_101025-d7\"]{font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading636_101025-d7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_101025-d7[data-kb-block=\"kb-adv-heading636_101025-d7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_101025-d7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_101025-d7[data-kb-block=\"kb-adv-heading636_101025-d7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading636_101025-d7 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_101025-d7\">Despu\u00e9s del procedimiento<\/h4>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading636_42855a-a0, .wp-block-kadence-advancedheading.kt-adv-heading636_42855a-a0[data-kb-block=\"kb-adv-heading636_42855a-a0\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_42855a-a0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_42855a-a0[data-kb-block=\"kb-adv-heading636_42855a-a0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_42855a-a0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_42855a-a0[data-kb-block=\"kb-adv-heading636_42855a-a0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading636_42855a-a0 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_42855a-a0\">Mant\u00e9n reposo relativo con la cabeza elevada durante los primeros d\u00edas. Evita la exposici\u00f3n al sol, el uso de maquillaje y movimientos bruscos del rostro. No retires los vendajes sin indicaci\u00f3n m\u00e9dica. Sigue estrictamente las indicaciones postoperatorias, incluyendo medicaci\u00f3n y asistencia a controles para asegurar una buena evoluci\u00f3n y cicatrizaci\u00f3n.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column636_4bf0dd-b8 > .kt-inside-inner-col{display:flex;}.kadence-column636_4bf0dd-b8 > .kt-inside-inner-col,.kadence-column636_4bf0dd-b8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_4bf0dd-b8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_4bf0dd-b8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column636_4bf0dd-b8 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column636_4bf0dd-b8 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column636_4bf0dd-b8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column636_4bf0dd-b8{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_4bf0dd-b8{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_4bf0dd-b8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column636_4bf0dd-b8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_4bf0dd-b8{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column636_4bf0dd-b8{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_4bf0dd-b8{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_4bf0dd-b8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column636_4bf0dd-b8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column636_4bf0dd-b8{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_4bf0dd-b8{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column636_4bf0dd-b8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column636_4bf0dd-b8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_4bf0dd-b8\"><div class=\"kt-inside-inner-col\"><style>.kb-image636_502303-48 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-image636_502303-48 img.kb-img, .kb-image636_502303-48 .kb-img img{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image636_502303-48 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"555\" height=\"377\" src=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/fac-01-686e128b12d06-1-e1752044239916.webp\" alt=\"\" class=\"kb-img wp-image-641\" srcset=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/fac-01-686e128b12d06-1-e1752044239916.webp 555w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/fac-01-686e128b12d06-1-e1752044239916-300x204.webp 300w, https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/fac-01-686e128b12d06-1-e1752044239916-500x340.webp 500w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id636_5095cc-a8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id636_5095cc-a8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id636_5095cc-a8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1300px;margin-left:auto;margin-right:auto;padding-top:80px;padding-bottom:80px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id636_5095cc-a8{background-color:#f8f8f8;}.kb-row-layout-id636_5095cc-a8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id636_5095cc-a8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id636_5095cc-a8 > .kt-row-column-wrap{padding-top:50px;padding-right:30px;padding-bottom:50px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id636_5095cc-a8 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column636_f11fc7-39 > .kt-inside-inner-col{box-shadow:20px 20px 30px 0px rgba(0, 0, 0, 0.2);}.kadence-column636_f11fc7-39 > .kt-inside-inner-col,.kadence-column636_f11fc7-39 > .kt-inside-inner-col:before{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kadence-column636_f11fc7-39 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_f11fc7-39 > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_f11fc7-39 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_f11fc7-39 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column636_f11fc7-39 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_f11fc7-39{position:relative;}@media all and (max-width: 1024px){.kadence-column636_f11fc7-39 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_f11fc7-39 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_f11fc7-39\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id636_cea28b-84 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id636_cea28b-84 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id636_cea28b-84 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id636_cea28b-84 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id636_cea28b-84 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id636_cea28b-84 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id636_cea28b-84 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id636_cea28b-84 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id636_cea28b-84 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id636_cea28b-84 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id636_cea28b-84 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id636_cea28b-84 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id636_cea28b-84 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id636_cea28b-84 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id636_cea28b-84 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column636_56c187-10 > .kt-inside-inner-col{min-height:555px;}.kadence-column636_56c187-10 > .kt-inside-inner-col,.kadence-column636_56c187-10 > .kt-inside-inner-col:before{border-top-left-radius:20px;border-bottom-left-radius:20px;}.kadence-column636_56c187-10 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_56c187-10 > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_56c187-10 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_56c187-10 > .kt-inside-inner-col{background-image:url('https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/06\/rectangle-13-6853a2292f57c.webp');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column636_56c187-10 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_56c187-10{position:relative;}@media all and (max-width: 1024px){.kadence-column636_56c187-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_56c187-10 > .kt-inside-inner-col,.kadence-column636_56c187-10 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kadence-column636_56c187-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_56c187-10\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column636_c790c1-48 > .kt-inside-inner-col{padding-top:40px;padding-right:40px;padding-bottom:0px;padding-left:40px;}.kadence-column636_c790c1-48 > .kt-inside-inner-col,.kadence-column636_c790c1-48 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_c790c1-48 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_c790c1-48 > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_c790c1-48 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_c790c1-48 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_c790c1-48{position:relative;}@media all and (max-width: 1024px){.kadence-column636_c790c1-48 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_c790c1-48 > .kt-inside-inner-col{padding-right:20px;padding-left:20px;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_c790c1-48\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_d81bca-e2, .wp-block-kadence-advancedheading.kt-adv-heading636_d81bca-e2[data-kb-block=\"kb-adv-heading636_d81bca-e2\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_d81bca-e2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_d81bca-e2[data-kb-block=\"kb-adv-heading636_d81bca-e2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_d81bca-e2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_d81bca-e2[data-kb-block=\"kb-adv-heading636_d81bca-e2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading636_d81bca-e2 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_d81bca-e2\">AGENDAR TU CITA<\/h4>\n\n\n<style>.kadence-form-803_ed68ca-89 .kb-form .kadence-blocks-form-field .kb-text-style-field, .kadence-form-803_ed68ca-89 .kb-form .kadence-blocks-form-field .kb-select-style-field{color:var(--global-palette7, #EDF2F7);font-size:15px;border-color:#abaec6;}.kadence-form-803_ed68ca-89 .kb-form .kadence-blocks-form-field > label{color:#848896;line-height:20px;font-family:Poppins;font-style:normal;font-weight:400;padding-top:8px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-form-803_ed68ca-89 .kb-form .kadence-blocks-form-field.kb-accept-form-field .kb-checkbox-style{font-size:20px;height:1em;}.kadence-form-803_ed68ca-89 .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);border-radius:10px;background:#22202d;}.kadence-form-803_ed68ca-89 .kb-form .kadence-blocks-form-field .kb-forms-submit:hover, .kadence-form-803_ed68ca-89 .kb-form .kadence-blocks-form-field .kb-forms-submit:focus {color:var(--global-palette9, #ffffff);background:var(--global-palette8, #F7FAFC);}.kadence-form-803_ed68ca-89 .kb-form .kadence-blocks-form-field .kb-forms-submit{font-size:18px;line-height:27px;font-family:Poppins;font-style:normal;font-weight:600;}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-803_ed68ca-89 kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Corrige los campos seleccionados \"><div class=\"kadence-blocks-form-field kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_0\" id=\"kb_field_803_ed68ca-89_0\" data-label=\"\" type=\"text\" placeholder=\"Nombre\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_1\" id=\"kb_field_803_ed68ca-89_1\" data-label=\"\" type=\"text\" placeholder=\"Procedimiento\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-1\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_2\" id=\"kb_field_803_ed68ca-89_2\" data-label=\"\" type=\"tel\" placeholder=\"Numero de celular \" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_3\" id=\"kb_field_803_ed68ca-89_3\" data-label=\"\" type=\"text\" placeholder=\"Ciudad\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-3\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-4 kb-field-desk-width-100 kb-input-size-standard\"><input name=\"kb_field_4\" id=\"kb_field_803_ed68ca-89_4\" data-label=\"\" type=\"email\" placeholder=\"E-mail\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-4\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-5 kb-field-desk-width-100 kb-input-size-standard\"><textarea name=\"kb_field_5\" id=\"kb_field_803_ed68ca-89_5\" data-label=\"Message\" type=\"textarea\" placeholder=\"Mensaje\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-5\" rows=\"4\" data-required=\"yes\"><\/textarea><\/div><div class=\"kadence-blocks-form-field kb-form-field-6 kb-field-desk-width-100 kb-input-size-standard kb-accept-form-field\"><a href=\"https:\/\/dariojuris.com\/politica-privacidad\/\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"kb-accept-link\">Ver pol\u00edticas de privacidad <\/a><input type=\"checkbox\" name=\"kb_field_6\" id=\"kb_field_803_ed68ca-89_6\" class=\"kb-field kb-checkbox-style kb-accept\" value=\"accept\" data-type=\"accept\" data-required=\"yes\"\/><label for=\"kb_field_803_ed68ca-89_6\">He le\u00eddo y acepto las pol\u00edticas de privacidad de la web<span class=\"required\">*<\/span><\/label><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"803_ed68ca-89\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"803\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><input type=\"hidden\" name=\"recaptcha_response\" class=\"kb_recaptcha_response kb_recaptcha_803_ed68ca-89\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-full\">Enviar<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-803_ed68ca-89 .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id636_74afeb-0a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id636_74afeb-0a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id636_74afeb-0a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;padding-top:90px;padding-bottom:90px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id636_74afeb-0a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id636_74afeb-0a > .kt-row-column-wrap{max-width:1440px;margin-left:auto;margin-right:auto;padding-top:60px;padding-right:50px;padding-bottom:60px;padding-left:50px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id636_74afeb-0a > .kt-row-column-wrap{padding-top:50px;padding-right:30px;padding-bottom:50px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id636_74afeb-0a alignnone wp-block-kadence-rowlayout\" id=\"FAQ\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column636_9ee3c2-77 > .kt-inside-inner-col,.kadence-column636_9ee3c2-77 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column636_9ee3c2-77 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column636_9ee3c2-77 > .kt-inside-inner-col{flex-direction:column;}.kadence-column636_9ee3c2-77 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column636_9ee3c2-77 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column636_9ee3c2-77{position:relative;}@media all and (max-width: 1024px){.kadence-column636_9ee3c2-77 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column636_9ee3c2-77 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column636_9ee3c2-77\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_f48b73-fa, .wp-block-kadence-advancedheading.kt-adv-heading636_f48b73-fa[data-kb-block=\"kb-adv-heading636_f48b73-fa\"]{text-align:center;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading636_f48b73-fa mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_f48b73-fa[data-kb-block=\"kb-adv-heading636_f48b73-fa\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_f48b73-fa img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_f48b73-fa[data-kb-block=\"kb-adv-heading636_f48b73-fa\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading636_f48b73-fa wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_f48b73-fa\">Preguntas Frecuentes<\/h4>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading636_c6daef-02, .wp-block-kadence-advancedheading.kt-adv-heading636_c6daef-02[data-kb-block=\"kb-adv-heading636_c6daef-02\"]{padding-bottom:40px;margin-right:-100px;margin-left:-100px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_c6daef-02 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_c6daef-02[data-kb-block=\"kb-adv-heading636_c6daef-02\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_c6daef-02 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_c6daef-02[data-kb-block=\"kb-adv-heading636_c6daef-02\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading636_c6daef-02, .wp-block-kadence-advancedheading.kt-adv-heading636_c6daef-02[data-kb-block=\"kb-adv-heading636_c6daef-02\"]{margin-right:0px;margin-left:0px;}}<\/style>\n<h2 class=\"kt-adv-heading636_c6daef-02 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_c6daef-02\">Todo lo que necesitas saber<\/h2>\n\n\n<style>.kt-accordion-id636_9f38c4-da .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:8px;}.kt-accordion-id636_9f38c4-da .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:#ffffff;padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px;}.kt-accordion-id636_9f38c4-da > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:1px solid rgba(34,32,45,0.22);border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#ffffff;font-size:21px;font-family:Poppins;font-weight:600;text-transform:none;color:var(--global-palette3, #1A202C);padding-top:16px;padding-right:10px;padding-bottom:6px;padding-left:16px;}.kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette8, #F7FAFC);}.kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette8, #F7FAFC);}.kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id636_9f38c4-da > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id636_9f38c4-da .kt-blocks-accordion-header:focus-visible{color:var(--global-palette4, #2D3748);background:#ffffff;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom:1px solid var(--global-palette4, #2D3748);border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette8, #F7FAFC);}.kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:var(--global-palette8, #F7FAFC);}.kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id636_9f38c4-da .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id636_9f38c4-da > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette4, #2D3748);background:#ffffff;border-top-color:#0e9cd1;border-top-style:solid;border-right-color:#0e9cd1;border-right-style:solid;border-bottom:1px solid var(--global-palette2, #2B6CB0);border-left-color:#0e9cd1;border-left-style:solid;}.kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette8, #F7FAFC);}.kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette8, #F7FAFC);}.kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id636_9f38c4-da:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}@media all and (max-width: 1024px){.kt-accordion-id636_9f38c4-da .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id636_9f38c4-da > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:1px solid rgba(34,32,45,0.22);border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id636_9f38c4-da > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id636_9f38c4-da .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom:1px solid var(--global-palette4, #2D3748);border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id636_9f38c4-da .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id636_9f38c4-da > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#0e9cd1;border-top-style:solid;border-right-color:#0e9cd1;border-right-style:solid;border-bottom:1px solid var(--global-palette2, #2B6CB0);border-left-color:#0e9cd1;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id636_9f38c4-da .kt-accordion-inner-wrap{display:block;}.kt-accordion-id636_9f38c4-da .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:8px;}.kt-accordion-id636_9f38c4-da .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id636_9f38c4-da > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:1px solid rgba(34,32,45,0.22);border-left:0px solid #f2f2f2;}.kt-accordion-id636_9f38c4-da > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id636_9f38c4-da .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom:1px solid var(--global-palette4, #2D3748);border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id636_9f38c4-da .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id636_9f38c4-da > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#0e9cd1;border-top-style:solid;border-right-color:#0e9cd1;border-right-style:solid;border-bottom:1px solid var(--global-palette2, #2B6CB0);border-left-color:#0e9cd1;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id636_9f38c4-da kt-accordion-has-5-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane636_336c5a-01\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>\u00bfCu\u00e1l es la mejor edad para un lifting facial?<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_b296c5-fe, .wp-block-kadence-advancedheading.kt-adv-heading636_b296c5-fe[data-kb-block=\"kb-adv-heading636_b296c5-fe\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_b296c5-fe mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_b296c5-fe[data-kb-block=\"kb-adv-heading636_b296c5-fe\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_b296c5-fe img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_b296c5-fe[data-kb-block=\"kb-adv-heading636_b296c5-fe\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading636_b296c5-fe wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_b296c5-fe\">Generalmente, el lifting facial es recomendado para personas entre los 40 y 60 a\u00f1os, pero puede variar seg\u00fan el estado de la piel.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane636_994c7f-d5\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u00bfQui\u00e9nes son candidatos para una bichectom\u00eda?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_fedec2-03, .wp-block-kadence-advancedheading.kt-adv-heading636_fedec2-03[data-kb-block=\"kb-adv-heading636_fedec2-03\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_fedec2-03 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_fedec2-03[data-kb-block=\"kb-adv-heading636_fedec2-03\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_fedec2-03 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_fedec2-03[data-kb-block=\"kb-adv-heading636_fedec2-03\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading636_fedec2-03 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_fedec2-03\">El procedimiento <strong>no es doloroso <\/strong>debido a que se realiza una preparaci\u00f3n m\u00ednima en cada diente.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane636_e686b6-48\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u00bfDuele el procedimiento?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_32db8b-d9, .wp-block-kadence-advancedheading.kt-adv-heading636_32db8b-d9[data-kb-block=\"kb-adv-heading636_32db8b-d9\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_32db8b-d9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_32db8b-d9[data-kb-block=\"kb-adv-heading636_32db8b-d9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_32db8b-d9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_32db8b-d9[data-kb-block=\"kb-adv-heading636_32db8b-d9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading636_32db8b-d9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_32db8b-d9\">No, se realiza con anestesia local, y las molestias postoperatorias son leves y controlables.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane636_166383-d0\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u00bfCu\u00e1ndo se ven los resultados finales?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_a3bf53-d8, .wp-block-kadence-advancedheading.kt-adv-heading636_a3bf53-d8[data-kb-block=\"kb-adv-heading636_a3bf53-d8\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_a3bf53-d8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_a3bf53-d8[data-kb-block=\"kb-adv-heading636_a3bf53-d8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_a3bf53-d8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_a3bf53-d8[data-kb-block=\"kb-adv-heading636_a3bf53-d8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading636_a3bf53-d8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_a3bf53-d8\">El tiempo necesario para completar el tratamiento depende de las caracter\u00edsticas y necesidades espec\u00edficas de cada paciente. En algunos casos, puede ser necesario realizar una cirug\u00eda periodontal antes de colocar las carillas, lo que requerir\u00eda un tiempo adicional para la cicatrizaci\u00f3n. Si el tratamiento consiste \u00fanicamente en la colocaci\u00f3n de carillas de cer\u00e1mica, el tiempo estimado es de aproximadamente 15 a 20 d\u00edas.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane636_aee8a0-d6\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u00bfQuedan cicatrices visibles?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading636_bd3710-f5, .wp-block-kadence-advancedheading.kt-adv-heading636_bd3710-f5[data-kb-block=\"kb-adv-heading636_bd3710-f5\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading636_bd3710-f5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading636_bd3710-f5[data-kb-block=\"kb-adv-heading636_bd3710-f5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading636_bd3710-f5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading636_bd3710-f5[data-kb-block=\"kb-adv-heading636_bd3710-f5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading636_bd3710-f5 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading636_bd3710-f5\">No, el desgaste es m\u00ednimo y solo se realiza en la capa superficial del esmalte, manteniendo la funcionalidad del diente<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Cirug\u00edas Faciales Lifting Facial \u2013 Ritidoplastia El paso de los a\u00f1os produce arrugas y ca\u00edda de la piel de la cara que se acompa\u00f1a de flacidez muscular del rostro, cambiando la expresi\u00f3n y acentuando pliegues caracter\u00edsticos del envejecimiento. Ventajas del procedimiento Nuestros resultados Antes y despu\u00e9s Paso a Paso del Procedimiento Paso 1 Paso 2&#8230;<\/p>","protected":false},"author":3,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"disable","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_vp_format_video_url":"","_vp_image_focal_point":[],"_joinchat":[],"footnotes":""},"portfolio_category":[],"portfolio_tag":[],"class_list":["post-636","portfolio","type-portfolio","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lifting Facial \u2013 Ritidoplastia - DR. Dario Juris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dariojuris.com\/en\/portfolio\/lifting-facial-ritidoplastia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lifting Facial \u2013 Ritidoplastia - DR. Dario Juris\" \/>\n<meta property=\"og:description\" content=\"Cirug\u00edas Faciales Lifting Facial \u2013 Ritidoplastia El paso de los a\u00f1os produce arrugas y ca\u00edda de la piel de la cara que se acompa\u00f1a de flacidez muscular del rostro, cambiando la expresi\u00f3n y acentuando pliegues caracter\u00edsticos del envejecimiento. Ventajas del procedimiento Nuestros resultados Antes y despu\u00e9s Paso a Paso del Procedimiento Paso 1 Paso 2...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dariojuris.com\/en\/portfolio\/lifting-facial-ritidoplastia\/\" \/>\n<meta property=\"og:site_name\" content=\"DR. Dario Juris\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-11T11:48:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/Iconos-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"128\" \/>\n\t<meta property=\"og:image:height\" content=\"128\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dariojuris.com\\\/portfolio\\\/lifting-facial-ritidoplastia\\\/\",\"url\":\"https:\\\/\\\/dariojuris.com\\\/portfolio\\\/lifting-facial-ritidoplastia\\\/\",\"name\":\"Lifting Facial \u2013 Ritidoplastia - DR. Dario Juris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dariojuris.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dariojuris.com\\\/portfolio\\\/lifting-facial-ritidoplastia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dariojuris.com\\\/portfolio\\\/lifting-facial-ritidoplastia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dariojuris.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Iconos-1.webp\",\"datePublished\":\"2025-07-09T06:24:51+00:00\",\"dateModified\":\"2025-07-11T11:48:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dariojuris.com\\\/portfolio\\\/lifting-facial-ritidoplastia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dariojuris.com\\\/portfolio\\\/lifting-facial-ritidoplastia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dariojuris.com\\\/portfolio\\\/lifting-facial-ritidoplastia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dariojuris.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Iconos-1.webp\",\"contentUrl\":\"https:\\\/\\\/dariojuris.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Iconos-1.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dariojuris.com\\\/portfolio\\\/lifting-facial-ritidoplastia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/dariojuris.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/dariojuris.com\\\/portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lifting Facial \u2013 Ritidoplastia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dariojuris.com\\\/#website\",\"url\":\"https:\\\/\\\/dariojuris.com\\\/\",\"name\":\"DR. Dario Juris\",\"description\":\"Dr. Dar\u00edo Juris \u2013 Cirujano pl\u00e1stico en Bogot\u00e1 con m\u00e1s de 14 a\u00f1os de experiencia y m\u00e1s de 4.000 intervenciones, especializado en procedimientos faciales y corporales como rinoplastia, aumento de senos, liposucci\u00f3n y abdominoplastia. Miembro de la SCCP, ISAPS y FILAP, ofrece seguridad y excelencia quir\u00fargica en cl\u00ednicas reconocidas de Bogot\u00e1.\",\"publisher\":{\"@id\":\"https:\\\/\\\/dariojuris.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dariojuris.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dariojuris.com\\\/#organization\",\"name\":\"DR. Dario Juris\",\"url\":\"https:\\\/\\\/dariojuris.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dariojuris.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dariojuris.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/image-6852c92cc59ea.webp\",\"contentUrl\":\"https:\\\/\\\/dariojuris.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/image-6852c92cc59ea.webp\",\"width\":85,\"height\":88,\"caption\":\"DR. Dario Juris\"},\"image\":{\"@id\":\"https:\\\/\\\/dariojuris.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lifting Facial \u2013 Ritidoplastia - DR. Dario Juris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dariojuris.com\/en\/portfolio\/lifting-facial-ritidoplastia\/","og_locale":"en_US","og_type":"article","og_title":"Lifting Facial \u2013 Ritidoplastia - DR. Dario Juris","og_description":"Cirug\u00edas Faciales Lifting Facial \u2013 Ritidoplastia El paso de los a\u00f1os produce arrugas y ca\u00edda de la piel de la cara que se acompa\u00f1a de flacidez muscular del rostro, cambiando la expresi\u00f3n y acentuando pliegues caracter\u00edsticos del envejecimiento. Ventajas del procedimiento Nuestros resultados Antes y despu\u00e9s Paso a Paso del Procedimiento Paso 1 Paso 2...","og_url":"https:\/\/dariojuris.com\/en\/portfolio\/lifting-facial-ritidoplastia\/","og_site_name":"DR. Dario Juris","article_modified_time":"2025-07-11T11:48:39+00:00","og_image":[{"width":128,"height":128,"url":"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/Iconos-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dariojuris.com\/portfolio\/lifting-facial-ritidoplastia\/","url":"https:\/\/dariojuris.com\/portfolio\/lifting-facial-ritidoplastia\/","name":"Lifting Facial \u2013 Ritidoplastia - DR. Dario Juris","isPartOf":{"@id":"https:\/\/dariojuris.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dariojuris.com\/portfolio\/lifting-facial-ritidoplastia\/#primaryimage"},"image":{"@id":"https:\/\/dariojuris.com\/portfolio\/lifting-facial-ritidoplastia\/#primaryimage"},"thumbnailUrl":"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/Iconos-1.webp","datePublished":"2025-07-09T06:24:51+00:00","dateModified":"2025-07-11T11:48:39+00:00","breadcrumb":{"@id":"https:\/\/dariojuris.com\/portfolio\/lifting-facial-ritidoplastia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dariojuris.com\/portfolio\/lifting-facial-ritidoplastia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dariojuris.com\/portfolio\/lifting-facial-ritidoplastia\/#primaryimage","url":"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/Iconos-1.webp","contentUrl":"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/07\/Iconos-1.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/dariojuris.com\/portfolio\/lifting-facial-ritidoplastia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dariojuris.com\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/dariojuris.com\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Lifting Facial \u2013 Ritidoplastia"}]},{"@type":"WebSite","@id":"https:\/\/dariojuris.com\/#website","url":"https:\/\/dariojuris.com\/","name":"DR. Dario Juris","description":"Dr. Dar\u00edo Juris \u2013 Cirujano pl\u00e1stico en Bogot\u00e1 con m\u00e1s de 14 a\u00f1os de experiencia y m\u00e1s de 4.000 intervenciones, especializado en procedimientos faciales y corporales como rinoplastia, aumento de senos, liposucci\u00f3n y abdominoplastia. Miembro de la SCCP, ISAPS y FILAP, ofrece seguridad y excelencia quir\u00fargica en cl\u00ednicas reconocidas de Bogot\u00e1.","publisher":{"@id":"https:\/\/dariojuris.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dariojuris.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dariojuris.com\/#organization","name":"DR. Dario Juris","url":"https:\/\/dariojuris.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dariojuris.com\/#\/schema\/logo\/image\/","url":"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/06\/image-6852c92cc59ea.webp","contentUrl":"https:\/\/dariojuris.com\/wp-content\/uploads\/2025\/06\/image-6852c92cc59ea.webp","width":85,"height":88,"caption":"DR. Dario Juris"},"image":{"@id":"https:\/\/dariojuris.com\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"design_santiago","author_link":"https:\/\/dariojuris.com\/en\/author\/design_santiago\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/portfolio\/636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/comments?post=636"}],"version-history":[{"count":4,"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/portfolio\/636\/revisions"}],"predecessor-version":[{"id":817,"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/portfolio\/636\/revisions\/817"}],"wp:attachment":[{"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/media?parent=636"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/portfolio_category?post=636"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/dariojuris.com\/en\/wp-json\/wp\/v2\/portfolio_tag?post=636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}